{"id":108308,"date":"2025-12-03T09:41:24","date_gmt":"2025-12-03T08:41:24","guid":{"rendered":"https:\/\/lutz-blades.com\/partner\/marocco\/"},"modified":"2026-05-19T10:59:48","modified_gmt":"2026-05-19T08:59:48","slug":"marocco","status":"publish","type":"partner","link":"https:\/\/lutz-blades.com\/it\/partner\/marocco\/","title":{"rendered":"Marocco"},"content":{"rendered":"<section class=\"gb-container gb-container-7e22a331 hero-home-wrap\">\n\n\t\t\t<!-- start:hero | Hook: 'px_hero_before' -->       \n            \n            <div class=\"hero hero-71775650 full --randomized\" data-slides=\"1\" data-start=\"0\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\r\n\t\t\t<!-- start:hero-slide | Hook: 'px_hero-slide_before' -->       \r\n                    \r\n            <div class=\"hero-slide hero-slide-325d7e68 has-mobile-image is-style-video\">\r\n\t\t\t\t<div class=\"hero-canvas\" data-aos=\"fade-right\">\r\n\t\t\t\t\t<h1 class=\"hero-headline\">PARTNER DI LUTZ BLADES in Marocco<\/h1>\t\t\t\t\t<span class=\"hero-subheadline subheadline\">Grazie ai nostri partner qualificati, le nostre lame sono disponibili in modo rapido e affidabile anche in Marocco, con la qualit\u00e0 apprezzata in tutto il mondo.<\/span>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"hero-media hero-media-video\" data-aos=\"fade-left\"><video id=\"hero-video\" muted playsinline poster=\"79043\" width=\"1920\" height=\"1080\" autoplay loop>\r\n\t\t\t\t\t\t\t<source src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/flyover_marokko.mp4\" type=\"video\/mp4\">\r\n\t\t\t\t\t\t<\/video><\/div>            <\/div>\r\n\t\t\t\t\r\n            <!-- end:hero-slide | Hook: 'px_hero-slide_after' -->\t\t\t\r\n\t\t\t\r\n\r\n\r\n            \n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\n\t\t\t<!-- end:hero-->        \n            \n<\/section>\n\n<div class=\"gb-container gb-container-e82f3731 sektion-erklaerender-text-zu-lutz\">\n<div class=\"gb-container gb-container-226933b2\">\n<div class=\"gb-container gb-container-9a7dd799\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:\">Produttore di lame industriali in MAROCCO<\/h2><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Precise, durevoli e su misura per le tue esigenze: da oltre 100 anni <strong>LUTZ BLADES produce lame industriali per applicazioni di taglio meccanico<\/strong>. I nostri oltre 400 dipendenti realizzano soluzioni complete per i clienti nei nostri siti produttivi europei di Solingen (Germania) e Nysa (Polonia), dalla lama fino alla progettazione di dispenser e imballaggi. Da svariati settori industriali alla tecnologia medica e di laboratorio, fino all&#8217;industria alimentare e all&#8217;artigianato, aziende rinomate in tutto il mondo si affidano al nostro know-how e alla precisione e affidabilit\u00e0 delle nostre lame.  <\/em><\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-10ba6757\">\n\n<figure class=\"gb-block-image gb-block-image-dd9931d8\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"394\" class=\"gb-image gb-image-dd9931d8\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/LutzBlades_24_106-1.jpg\" alt=\"\"  srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/LutzBlades_24_106-1.jpg 700w, https:\/\/lutz-blades.com\/wp-content\/uploads\/LutzBlades_24_106-1-300x169.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n<\/div>\n<\/div>\n\n<section class=\"gb-container gb-container-d1667446 infinite-loop-carousel-wrapper gb-container-white\">\n<div class=\"gb-container gb-container-84638921 infinite-loop-carousel\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-1024x640.png\" alt=\"\" class=\"wp-image-93285\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-1024x640.png 1024w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-300x188.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-768x480.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-1536x960.png 1536w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-800x500.png 800w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-1200x750.png 1200w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-400x250.png 400w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-4.png\" alt=\"\" class=\"wp-image-93313\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-4.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-4-300x188.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-4-400x250.png 400w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-3.png\" alt=\"\" class=\"wp-image-93306\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-3.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-3-300x188.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-3-400x250.png 400w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-2.png\" alt=\"\" class=\"wp-image-93299\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-2.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-2-300x188.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-2-400x250.png 400w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-1024x640.png\" alt=\"\" class=\"wp-image-93285\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-1024x640.png 1024w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-300x188.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-768x480.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-1536x960.png 1536w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-800x500.png 800w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-1200x750.png 1200w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5-400x250.png 400w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-5.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-1.png\" alt=\"\" class=\"wp-image-93292\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-1.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-1-300x188.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-1-400x250.png 400w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-3.png\" alt=\"\" class=\"wp-image-93306\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-3.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-3-300x188.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-3-400x250.png 400w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-4.png\" alt=\"\" class=\"wp-image-93313\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-4.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-4-300x188.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-4-400x250.png 400w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-2.png\" alt=\"\" class=\"wp-image-93299\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-2.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-2-300x188.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-2-400x250.png 400w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-1.png\" alt=\"\" class=\"wp-image-93292\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-1.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-1-300x188.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-partner-galerie-1-400x250.png 400w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n<\/div>\n<\/section>\n<\/div>\n\n<section class=\"gb-container gb-container-f2323613 section-partner-details gb-container-white\">\n<div class=\"gb-container gb-container-0760924a\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-0d2b43ad\">\n<div class=\"gb-grid-column gb-grid-column-47fa121e\"><div class=\"gb-container gb-container-47fa121e\" data-aos=\"fade-left\">\n<div class=\"gb-container gb-container-1a1ee47e\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"45\" height=\"45\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/flag_mar-1.svg\" alt=\"\" class=\"wp-image-95854\"\/><\/figure>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:\">Maghreb Automation Offshore<\/h2><\/div>\n\n<\/div>\n\n<div class=\"gb-container gb-container-13cf4a90\">\n<div class=\"gb-container gb-container-83b95394\">\n\n<p class=\"wp-block-paragraph\"><strong>Maghreb Automation Offshore<\/strong> \u00e8 un&#8217;azienda industriale e di servizi marocchina con sede a Tangeri (Zone Franche d\u2019Exportation, Marocco), specializzata in automazione industriale, consulenza tecnica e manutenzione. L&#8217;azienda supporta progetti industriali e offshore con soluzioni di automazione e controllo, oltre a servizi accessori per migliorare i processi produttivi e operativi in impianti tecnici e automatizzati. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mission:<\/strong><br>Fornire ai nostri clienti soluzioni pratiche di automazione e manutenzione che aumentino l&#8217;efficienza operativa, la sicurezza dei processi e le prestazioni tecniche in ambienti industriali e offshore. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vision:<\/strong><br>Essere un partner affidabile e competente per i servizi di automazione, controllo e assistenza tecnica nel settore industriale e offshore marocchino, attraverso soluzioni orientate al cliente, competenza tecnica e ottimizzazione continua delle prestazioni.<\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-cb59d4bc\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/\/Lutz-Image-1-1024x683.jpg\" alt=\"\" class=\"wp-image-106128\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/Lutz-Image-1-1024x683.jpg 1024w, https:\/\/lutz-blades.com\/wp-content\/uploads\/Lutz-Image-1-300x200.jpg 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/Lutz-Image-1-768x512.jpg 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/Lutz-Image-1-1536x1025.jpg 1536w, https:\/\/lutz-blades.com\/wp-content\/uploads\/Lutz-Image-1-2048x1366.jpg 2048w, https:\/\/lutz-blades.com\/wp-content\/uploads\/Lutz-Image-1-750x500.jpg 750w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-21d777f5 taxonomy-grid-wrapper\">\n\n<p class=\"has-color-brand-color has-text-color has-link-color wp-elements-a249bc0717a9737db429106f74a4c52c wp-block-paragraph\"><strong>Settori di applicazione<\/strong><\/p>\n\n\n\r\n            \r\n            <div class=\"taxonomy-grid taxonomy-grid-a70b9bdb taxonomy-grid\">\r\n                <div class=\"taxonomy-grid__inner\">\r\n                    \r\n                        <a class=\"taxonomy-grid__item term-id-14\"                          \r\n                           data-branche-master-id=\"14\"\r\n                           data-branche-master-slug=\"folienherstellung\">\r\n\r\n                                                            <span class=\"taxonomy-grid__icon\">\r\n                                    <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" width=\"40\" height=\"40\" version=\"1.1\" viewBox=\"0 0 40 40\"><defs><style> .cls-1 { fill: #013064; stroke-width: 0px; } <\/style><\/defs><path class=\"cls-1 taxonomy-grid__icon-svg\" d=\"M15.2,14.2c-1.1,0-2.2.3-3.2,1s-1.7,1.5-2.1,2.6-.6,2.2-.3,3.3c.2,1.1.8,2.1,1.6,2.9.8.8,1.8,1.4,2.9,1.6.4,0,.8.1,1.1.1.8,0,1.5-.1,2.2-.4,1-.4,2-1.2,2.6-2.1.6-1,1-2,1-3.2s-.6-3-1.7-4.1-2.5-1.7-4.1-1.7ZM18.6,22.2c-.5.7-1.1,1.2-1.8,1.5-.7.3-1.6.4-2.3.2s-1.5-.5-2.1-1.1c-.6-.6-.9-1.3-1.1-2.1-.2-.8,0-1.6.2-2.3.3-.7.8-1.4,1.5-1.8.7-.5,1.4-.7,2.2-.7s2.1.4,2.9,1.2,1.2,1.8,1.2,2.9-.2,1.6-.7,2.2Z\"><\/path><path class=\"cls-1\" d=\"M36.7,30c-4-4-8.4-4-11.4-3.2,1.3-2,2.1-4.3,2.1-6.8,0-6.7-5.5-12.2-12.2-12.2S3,13.3,3,20s5.5,12.2,12.2,12.2,4.9-.8,6.9-2.1c0,0,0,0,0,0,.3-.2,7.1-5,13.4,1.2.2.2.4.2.6.2s.4,0,.6-.2c.3-.3.3-.9,0-1.2h0ZM4.7,20c0-5.8,4.7-10.5,10.5-10.5s10.5,4.7,10.5,10.5-4.7,10.5-10.5,10.5-10.5-4.7-10.5-10.5Z\"><\/path><\/svg>                                 <\/span>\r\n                            \r\n                            <span class=\"taxonomy-grid__label\">\r\n                                Folienherstellung                            <\/span>\r\n                        <\/a>\r\n\r\n                    \r\n                        <a class=\"taxonomy-grid__item term-id-22\"                          \r\n                           data-branche-master-id=\"22\"\r\n                           data-branche-master-slug=\"chemiefaser-herstellung\">\r\n\r\n                                                            <span class=\"taxonomy-grid__icon\">\r\n                                    <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" width=\"40\" height=\"40\" version=\"1.1\" viewBox=\"0 0 40 40\"><defs><style> .cls-1 { fill: #013064; stroke-width: 0px; } <\/style><\/defs><path class=\"cls-1 taxonomy-grid__icon-svg\" d=\"M20.7,18.8c-2.3-1.4-2.8-7.2-2.8-9.4s-.4-.9-.9-.9-.9.4-.9.9,0,5.2,1.5,8.4c-4.9-2.6-5-8.1-5-8.4,0-.5-.4-.9-.9-.9h0c-.5,0-.9.4-.9.9s0,4.4,3.1,7.7c-6.3-2.8-6.5-7.4-6.5-7.7,0-.5-.4-.9-.8-.9s-.8.4-.8.9.2,9,13.9,11c0,0,0,0,.1,0,1.9,1.4,2.6,6.9,2.6,10.2,0,.5.4.9.9.9h0c.5,0,.9-.4.9-.9,0-.7,0-5.6-1.5-9,4.5,2.8,4.6,8.7,4.6,9,0,.5.4.9.9.9h0c.5,0,.9-.4.9-.9s0-4.8-3-8.4c6.1,3,6.2,8.1,6.2,8.4,0,.5.4.9.8.9s.8-.4.8-.9-.2-9.6-13.4-11.8h0Z\"><\/path><\/svg>                                 <\/span>\r\n                            \r\n                            <span class=\"taxonomy-grid__label\">\r\n                                Chemiefaser-Herstellung                            <\/span>\r\n                        <\/a>\r\n\r\n                    \r\n                        <a class=\"taxonomy-grid__item term-id-494\"                          \r\n                           data-branche-master-id=\"494\"\r\n                           data-branche-master-slug=\"glasfaser-herstellung\">\r\n\r\n                                                            <span class=\"taxonomy-grid__icon\">\r\n                                    <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" width=\"40\" height=\"40\" version=\"1.1\" viewBox=\"0 0 40 40\"><defs><style> .cls-1 { fill: #013064; stroke-width: 0px; } <\/style><\/defs><path class=\"cls-1 taxonomy-grid__icon-svg\" d=\"M25.8,28.3c-2.5-.4-7-3.2-8.4-4.7-2.8-3-4-4.7-4.7-6.9-.4-1.4-.7-3.2.2-4.4.5-.6,1.1-.8,1.6-.8s.4.3.2.4c-.3.3-.6.7-.6,1.6s.5,3,1.3,4.4c1,1.7,1.7,3.2,5.8,6.3,2,1.5,4.5,2.5,6.6,3.3.2,0,.2.2,0,.4-.3.2-1.3.5-2.1.4h0Z\"><\/path><path class=\"cls-1\" d=\"M19.6,29.2c-2.9-1.4-4.4-3.1-5.5-4.3-2.2-2.5-3.1-4-3.7-5.8-.4-1.1-.7-1.8-.6-3.1.1-1,.9-2.1,1.4-2.7.1-.2.4,0,.4.2-.2,1-.3,1.9,0,3.2.3,1.2.7,2.1,1.3,3.2.7,1.3,2.1,3.2,3.7,4.8,1.9,1.9,4.4,3.4,6.6,4.2.3.1.2.5,0,.5-.7.2-2.4.3-3.6-.3h0,0Z\"><\/path><path class=\"cls-1\" d=\"M13.2,27.7c-1.1-.8-1.6-1.1-2.9-2.7-1.2-1.5-1.7-2.4-2.2-3.6-.6-1.5-.6-2.2-.6-3,0-.8.6-1.5,1-2,.2-.2.4,0,.4.2-.2,1.5,0,2.3.1,2.9.3.8.7,1.5,1.1,2.3.6.9,1.2,2,2.6,3.7.7.8,1.9,2,3,2.8.2.2,0,.5-.2.5-.7,0-1.6-.4-2.5-1h0s0,0,0,0Z\"><\/path><path class=\"cls-1\" d=\"M6.4,23.2c-.7-1.5-.4-2.7,0-3.3.1-.2.4-.2.5,0,0,.6.3,1.4.9,2.6.6,1.2,1.9,3,2.8,3.9.2.2,0,.5-.3.4-1-.4-2.8-1.3-3.9-3.8h0Z\"><\/path><path class=\"cls-1\" d=\"M20.2,16.4s-.1,0-.6-.8c-.5-.6-.4-1-.4-1,1.2-.6,2.1-1.3,2.6-1.8,1.1-1.1.5-2.3.5-2.3.6,0,1.8,0,1.6,1.9-.1,2-3.2,3.7-3.7,4h0Z\"><\/path><path class=\"cls-1\" d=\"M29.6,26.8c-1.3,0-2.8-.8-3.6-1.3-2.4-1.3-4.1-2.5-5.5-3.7-2.4-2-3.9-4.2-4.7-6.3-.6-1.7-.6-3.2.2-4.1,1.2-1.5,3.1-1.2,4.9-.3,0,0,.6,1.2-.9,1.6-1.1.3-1.9-.4-2.4.1-.2.2-.2.9.2,1.9.7,1.8,2.2,3.7,4.2,5.5,1.6,1.4,3.8,3.3,9.6,5.4.2,0,.3.4,0,.6-.5.3-1.2.6-2,.6h0s0,0,0,0Z\"><\/path><path class=\"cls-1\" d=\"M22.6,19.2c1.4-.9,2.3-1.8,3.1-2.9.9-1.2,1.7-2.8,1.3-4.2-.2-.8-.8-1.1-1.2-1.3-.2,0-.4.2-.3.4.2.4.4.9,0,1.7-.3.9-1.5,2.6-2.7,3.7-.5.4-1,.8-1.5,1.2.4.5.9.9,1.4,1.4h0s0,0,0,0Z\"><\/path><path class=\"cls-1\" d=\"M29,17.7c.8-1.2,1.4-2.9.9-4.4-.2-.5-.5-.9-.7-1.1-.2-.2-.6,0-.5.2,0,.4,0,1.1-.2,1.8-.2.9-1.2,2.8-2.4,3.9-.6.7-1.2,1.3-2.2,2,.4.4,1,.7,1.6,1.1,1.7-1.3,2.6-2.4,3.5-3.7h0s0,0,0,0Z\"><\/path><path class=\"cls-1\" d=\"M31.3,20.5c.8-1.2,1.6-2.9,1.1-4.3-.2-.5-.4-.9-.6-1.2-.2-.2-.6,0-.5.2,0,.4,0,1.1-.2,1.8-.3.9-1.3,2.7-2.5,3.8-.5.5-.9.9-1.5,1.4.6.3,1.2.6,1.9.9,1.1-.9,1.8-1.7,2.5-2.7h0s0,0,0,0Z\"><\/path><path class=\"cls-1\" d=\"M32.2,24.6c.2-.2.5-.5.7-.8,1.2-1.5,1.2-2.9,1-3.7,0-.3-.5-.3-.6,0-.3.6-.8,1.5-1.8,2.7-.4.4-.7.8-1.1,1.1.5.2,1,.4,1.6.6,0,0,0,0,.1,0h0s0,0,0,0Z\"><\/path><\/svg>                                 <\/span>\r\n                            \r\n                            <span class=\"taxonomy-grid__label\">\r\n                                Glasfaser-Herstellung                            <\/span>\r\n                        <\/a>\r\n\r\n                    \r\n                        <a class=\"taxonomy-grid__item term-id-21\"                          \r\n                           data-branche-master-id=\"21\"\r\n                           data-branche-master-slug=\"automobilindustrie\">\r\n\r\n                                                            <span class=\"taxonomy-grid__icon\">\r\n                                    <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" width=\"40\" height=\"40\" version=\"1.1\" viewBox=\"0 0 40 40\"><defs><style> .cls-1 { fill: #013064; stroke-width: 0px; } <\/style><\/defs><path class=\"cls-1 taxonomy-grid__icon-svg\" d=\"M38.7,17.5c-1.3-1.4-4-2.1-8.4-2.1h-1c-.7-.7-4.4-4.2-11.2-4.2s-12.1,2.3-13,2.7l-2.8.5c-1.1.2-2,1.2-2,2.3v4.4c0,1,.4,1.9,1,2.6.7.8,1.8,1.3,2.9,1.3h.2c.4,2.1,2.2,3.7,4.5,3.7s4.1-1.6,4.5-3.7h13.3c.4,2.1,2.2,3.7,4.5,3.7s4.1-1.6,4.5-3.7h1.8c1.2,0,2.1-.9,2.1-2.1v-3.2c0-.8-.3-1.6-.9-2.2h0,0ZM26.7,15.4h-11.7l-1-2.3c1.3-.2,2.6-.3,4.1-.3,4.1,0,7,1.5,8.6,2.6h0ZM9,27.1c-1.6,0-2.9-1.3-2.9-2.9s1.3-2.9,2.9-2.9,2.9,1.3,2.9,2.9-1.3,2.9-2.9,2.9ZM31.2,27.1c-1.6,0-2.9-1.3-2.9-2.9s1.3-2.9,2.9-2.9,2.9,1.3,2.9,2.9-1.3,2.9-2.9,2.9ZM37.9,22.9c0,.2-.2.4-.4.4h-1.8c-.4-2.1-2.2-3.7-4.5-3.7s-4.1,1.6-4.5,3.7h-13.3c-.4-2.1-2.2-3.7-4.5-3.7s-4.1,1.6-4.5,3.7h-.2c-.6,0-1.2-.3-1.7-.7-.4-.4-.6-1-.6-1.5v-4.4c0-.3.2-.6.6-.7l2.8-.5s.2,0,.2,0c0,0,2.7-1.3,6.6-2l3.2,7.4c.1.3.4.5.8.5s.2,0,.3,0c.4-.2.6-.7.4-1.1l-1.3-3.1h14.6c4.7,0,6.5.9,7.2,1.6.3.3.4.7.4,1.1v3.2h0s0,0,0,0Z\"><\/path><\/svg>                                 <\/span>\r\n                            \r\n                            <span class=\"taxonomy-grid__label\">\r\n                                Automobilindustrie                            <\/span>\r\n                        <\/a>\r\n\r\n                    \r\n                        <a class=\"taxonomy-grid__item term-id-19\"                          \r\n                           data-branche-master-id=\"19\"\r\n                           data-branche-master-slug=\"textilherstellung\">\r\n\r\n                                                            <span class=\"taxonomy-grid__icon\">\r\n                                    <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" width=\"40\" height=\"40\" version=\"1.1\" viewBox=\"0 0 40 40\"><defs><style> .cls-1 { fill: #013064; stroke-width: 0px; } <\/style><\/defs><path class=\"cls-1 taxonomy-grid__icon-svg\" d=\"M31.5,23.8c-.9,0-1.3-.2-1.9-.5-.6-.4-1.4-.8-2.7-.8s-2,.4-2.6.7c0-.2-.1-.5-.1-.9,0-.9.2-1.3.5-1.9.4-.6.8-1.4.8-2.7s0-.9-.1-1.2c.4-.2.8-.3,1.5-.3s1.3.2,1.9.5c.6.4,1.4.8,2.7.8s.8-.4.8-.9-.4-.9-.9-.9c-.9,0-1.3-.2-1.9-.6-.6-.4-1.4-.8-2.7-.8s-1.6.2-2.2.5c-.3-.5-.5-.9-.5-1.8s.2-1.3.5-1.9c.4-.6.8-1.4.8-2.7s-.4-.8-.9-.8-.9.4-.9.8c0,.9-.2,1.3-.5,1.9-.4.6-.8,1.4-.8,2.7s.4,2,.7,2.6c-.2,0-.5.1-.9.1-.9,0-1.3-.2-1.9-.6-.6-.4-1.4-.8-2.7-.8s-.9,0-1.2.1c-.2-.4-.3-.8-.3-1.5s.2-1.3.5-1.9c.4-.6.8-1.4.8-2.7s-.4-.8-.9-.8-.9.4-.9.8c0,.9-.2,1.3-.6,1.9-.4.6-.8,1.4-.8,2.7s.2,1.6.5,2.2c-.5.3-.9.5-1.8.5s-1.3-.2-1.9-.6c-.6-.4-1.4-.8-2.7-.8s-.8.4-.8.9.4.9.8.9c.9,0,1.3.2,1.9.5.6.4,1.4.8,2.7.8s2-.4,2.6-.7c0,.2.1.5.1.9,0,.9-.2,1.3-.6,1.9-.4.6-.8,1.4-.8,2.7s0,.9.1,1.2c-.4.2-.8.3-1.5.3s-1.3-.2-1.9-.5c-.6-.4-1.4-.8-2.7-.8s-.8.4-.8.9.4.9.8.9c.9,0,1.3.2,1.9.5.6.4,1.4.8,2.7.8s1.6-.2,2.2-.5c.3.5.5.9.5,1.8s-.2,1.3-.6,1.9c-.4.6-.8,1.4-.8,2.7s.4.8.9.8.9-.4.9-.9c0-.9.2-1.3.5-1.9.4-.6.8-1.4.8-2.7s-.4-2-.7-2.6c.2,0,.5-.1.9-.1.9,0,1.3.2,1.9.5.6.4,1.4.8,2.7.8s.9,0,1.2-.1c.2.4.3.8.3,1.5s-.2,1.3-.5,1.9c-.4.6-.8,1.4-.8,2.7s.4.8.9.8.9-.4.9-.9c0-.9.2-1.3.5-1.9.4-.6.8-1.4.8-2.7s-.2-1.6-.5-2.2c.5-.3.9-.5,1.8-.5s1.4.2,1.9.5c.6.4,1.4.8,2.7.8s.8-.4.8-.9-.4-.9-.9-.9h0ZM20.4,23.3c-.6-.4-1.4-.8-2.7-.8s-1.1,0-1.5.2c0-.1,0-.3,0-.4,0-.9.2-1.3.5-1.9.4-.6.8-1.4.8-2.7s0-1.1-.2-1.5c.1,0,.3,0,.4,0,.9,0,1.3.2,1.9.5.6.4,1.4.8,2.7.8s1.1,0,1.5-.2c0,.1,0,.3,0,.4,0,.9-.2,1.3-.5,1.9-.4.6-.8,1.4-.8,2.7s0,1.1.2,1.5c-.1,0-.3,0-.4,0-.9,0-1.3-.2-1.9-.5h0Z\"><\/path><\/svg>                                 <\/span>\r\n                            \r\n                            <span class=\"taxonomy-grid__label\">\r\n                                Textilherstellung                            <\/span>\r\n                        <\/a>\r\n\r\n                    \r\n                        <a class=\"taxonomy-grid__item term-id-18\"                          \r\n                           data-branche-master-id=\"18\"\r\n                           data-branche-master-slug=\"gartentechnik\">\r\n\r\n                                                            <span class=\"taxonomy-grid__icon\">\r\n                                    <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" width=\"40\" height=\"40\" version=\"1.1\" viewBox=\"0 0 40 40\"><defs><style> .cls-1 { fill: #013064; stroke-width: 0px; } <\/style><\/defs><path class=\"cls-1 taxonomy-grid__icon-svg\" d=\"M33.4,11.5c-.3-.7-.7-1.3-1.2-1.9s-1.1-.9-1.9-1.2c-.7-.3-1.4-.4-2.2-.4h0c-1,0-1.9.2-2.7.7-.6-1.4-1.5-2.6-2.7-3.4-1.6-1.1-3.5-1.6-5.4-1.4-1.9.2-3.6,1.1-4.9,2.5-1.1,1.2-1.8,2.8-1.9,4.5-1.2.3-2.2.9-3,1.8-1,1.1-1.5,2.5-1.4,4,0,1.5.7,2.8,1.8,3.9,1.1,1.1,2.7,1.6,4.2,1.6.4,1,1.1,1.9,1.9,2.5.3.3.5.4.7.7h0s.3,2.6.5,4.2c.1,1.1-1.1,4.2-4.8,4.9-.5,0-.8.5-.7,1,0,.4.4.7.8.7s.1,0,.2,0c4.4-.8,6.5-4.5,6.2-6.8-.1-1.1-.3-2.8-.4-3.6.4,0,.8.1,1.2.1h0c1.1,0,2.2-.3,3.2-.9.3.4.7.8,1.1,1.1-.5.6-2.7,3.5-2,6.3.5,1.7,2,3,4.4,3.8,0,0,.2,0,.3,0,.4,0,.7-.2.8-.6.1-.5-.1-.9-.5-1.1-1.9-.6-3-1.5-3.3-2.6-.6-2.2,1.7-4.8,1.7-4.8,0,0,0-.1.1-.2.7.3,1.4.4,2.2.4s1,0,1.5-.2c1.3-.3,2.5-1.1,3.3-2.1s1.3-2.4,1.3-3.7-.2-1.9-.7-2.8c.7-.4,1.3-1,1.8-1.6.7-1,1-2.1,1-3.2,0-.8-.1-1.5-.4-2.2h0ZM32.2,13.7c0,.8-.2,1.6-.7,2.3s-1.1,1.2-1.9,1.5l-1.1.4.7.9c.6.7.9,1.6.9,2.6s-.3,1.9-.9,2.7-1.4,1.3-2.4,1.5-1.9.1-2.8-.2-1.6-1.1-2.1-1.9l-.5-.9-.8.7c-.8.7-1.8,1.1-2.8,1.1h0c-1,0-1.9-.3-2.6-.9-.8-.6-1.3-1.4-1.6-2.3l-.2-.8h-.8c-.2.2-.5.2-.7.2-1,0-2-.4-2.8-1.1-.8-.7-1.2-1.7-1.2-2.7,0-1,.3-2,1-2.8s1.6-1.3,2.7-1.4h.8v-.9c0-1.5.5-2.9,1.5-4s2.3-1.8,3.8-2c1.5-.2,3,.2,4.2,1.1,1.2.9,2.1,2.1,2.4,3.6l.3,1.4,1.1-1c.7-.6,1.6-1,2.6-1h0c.5,0,1,.1,1.5.3.5.2.9.5,1.3.9s.7.8.9,1.3.3,1,.3,1.5h0Z\"><\/path><\/svg>                                 <\/span>\r\n                            \r\n                            <span class=\"taxonomy-grid__label\">\r\n                                Gartentechnik                            <\/span>\r\n                        <\/a>\r\n\r\n                    \r\n                        <a class=\"taxonomy-grid__item term-id-481\"                          \r\n                           data-branche-master-id=\"481\"\r\n                           data-branche-master-slug=\"medizin-und-labor\">\r\n\r\n                                                            <span class=\"taxonomy-grid__icon\">\r\n                                    <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" width=\"40\" height=\"40\" version=\"1.1\" viewBox=\"0 0 40 40\"><defs><style> .cls-1 { fill: #013064; stroke-width: 0px; } <\/style><\/defs><path class=\"cls-1 taxonomy-grid__icon-svg\" d=\"M9.4,32.1h10c.5,0,.9-.4.9-.9s-.4-.9-.9-.9h-10c-.5,0-.9.4-.9.9s.4.9.8.9Z\"><\/path><path class=\"cls-1\" d=\"M30.4,20.4c-.7-1.3-1.8-2.5-3.1-3.3-.5-.3-1-.5-1.5-.7,0,0,0-.1,0-.2,0-.4,0-.9-.2-1.3-.2-.4-.4-.8-.7-1.1s-.2-.2-.3-.3l.9-2.2c0-.2,0-.4,0-.6s-.2-.4-.5-.5l-.8-.4,1.3-3.2c.2-.4,0-.9-.5-1.1l-2.6-1.1c-.2,0-.4,0-.6,0s-.4.2-.5.5l-1.3,3.2-.8-.3c-.4-.2-.9,0-1.1.5l-5.7,13.7c0,.2,0,.4,0,.6s.2.4.5.5l.8.4-1,2.5c-.2.4,0,.9.5,1.1l2.6,1.1c.1,0,.2,0,.3,0s.2,0,.3,0c.2,0,.4-.2.5-.5l1-2.5.8.4c.1,0,.2,0,.3,0,.3,0,.6-.2.8-.5l2.4-5.7c.1,0,.3,0,.4,0,.4,0,.9,0,1.3-.2.6-.2,1.1-.7,1.5-1.2,0,0,0,0,0,0,.4.1.8.3,1.2.5,1,.7,1.9,1.6,2.5,2.7.6,1.1.9,2.3.9,3.5v9.1H9.4c-.5,0-.9.4-.9.8s.4.8.9.8h21.1c.5,0,.9-.4.9-.8v-10c0-1.5-.3-3-1.1-4.4ZM15.4,26.3l-1.1-.4.4-1,1.1.4-.4,1ZM22.4,6.4l1,.4-1,2.4-1-.4,1-2.4h0ZM18.4,23.7l-4.3-1.8,5-12.2.8.3h0l2.6,1.1h0l.8.3-.6,1.4c-.1,0-.3,0-.4,0h0c-.7,0-1.3.2-1.8.6-.5.4-1,.9-1.2,1.5-.2.6-.3,1.3-.2,1.9s.4,1.2.9,1.7c.1.1.2.2.3.3l-2,4.9h0ZM23.1,17.7c-.3.1-.6.2-.9,0-.3,0-.6-.2-.8-.4-.2-.2-.4-.5-.4-.8,0-.3,0-.6,0-.9s.3-.5.6-.7.6-.3.9-.3h0c.2,0,.4,0,.6.1s.4.2.5.4c.1.1.3.3.4.5,0,.2.1.4.1.6h0c0,.3,0,.6-.3.9-.2.3-.4.5-.7.6h0Z\"><\/path><\/svg>                                 <\/span>\r\n                            \r\n                            <span class=\"taxonomy-grid__label\">\r\n                                Medizin und Labor                            <\/span>\r\n                        <\/a>\r\n\r\n                    \r\n                        <a class=\"taxonomy-grid__item term-id-15\"                          \r\n                           data-branche-master-id=\"15\"\r\n                           data-branche-master-slug=\"heimwerkermaerkte\">\r\n\r\n                                                            <span class=\"taxonomy-grid__icon\">\r\n                                    <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" width=\"40\" height=\"40\" version=\"1.1\" viewBox=\"0 0 40 40\"><defs><style> .cls-1 { fill: #013064; stroke-width: 0px; } <\/style><\/defs><path class=\"cls-1 taxonomy-grid__icon-svg\" d=\"M28,29.1c.2.1.4.2.5.2s.4,0,.5-.2h0c.1-.2.2-.4.2-.6s0-.4-.2-.5l-4.9-4.9c-.3-.3-.8-.3-1.1,0s-.2.4-.2.5,0,.4.2.5l4.9,4.9h0Z\"><\/path><path class=\"cls-1\" d=\"M14.5,28c0-.7-.5-1.3-1-1.7-.1-.1-.2-.2-.3-.3l-.4-.5v.2c-.4-.2-1-.2-1.5-.2h-.4c-.5,0-.9.2-1.2.5,0,0-.2.2-.3.3-.5.5-1.1,1-1,1.7v.3c0,.6,0,1.5.5,2l.7.7c.4.5,1,.5,1.6.5h.7c.5,0,.9-.2,1.2-.5,0,0,.2-.2.3-.3.5-.5,1.1-1,1-1.7v-1.1h0ZM13.1,28v1.1c0,0,0,.1,0,.2l-.7.7c0,0-.2.1-.2.1h-1.1c0,0-.1,0-.2,0l-.7-.7c0,0-.1-.2-.1-.2v-1.1c0,0,0-.1,0-.2l.7-.7c0,0,.2-.1.2-.1h1.1c0,0,.1,0,.2,0l.7.7c0,0,.1.2.1.2Z\"><\/path><path class=\"cls-1\" d=\"M24.8,20h0c-.2,0-.5-.1-.8-.2l1.8-1.8c.2-.2.4-.2.7-.2,1.5.3,2.9,0,4.2-.8,1.2-.8,2.1-2.1,2.4-3.5.2-.8.2-1.7,0-2.5,0-.2-.2-.3-.3-.4-.2-.1-.4-.1-.5,0-.1,0-.2,0-.3.1l-2.1,2.1c0,0-.2,0-.2,0l-2-.2c0,0-.1,0-.2-.2l-.2-2c0,0,0-.2,0-.2l2.1-2.1c.3-.3.3-.8,0-1,0,0-.2,0-.3-.1-1.9-.5-3.8,0-5.2,1.4-1.4,1.4-2,3.3-1.6,5.1,0,.2,0,.5-.2.6l-2.8,2.8-6.5-6.4c0,0-.2-.2-.2-.2v-.2c-.3-.7-.6-1.6-1.4-1.9l-2.2-1.2c-.5-.2-1-.2-1.4.2l-.5.5c-.4.4-.5.9-.2,1.4l1.2,2.2c.2.5.6.8,1.1,1,0,0,.2,0,.4.1.3,0,.8.2.9.4l6.4,6.5-4.1,4c-.3.3-.8.5-1.2.5-2.6-.1-4.8,2-4.9,4.6v.4c0,1.7,1.1,3.2,2.7,4,.7.3,1.4.5,2.1.5s1.9-.3,2.7-.9c1.3-.9,2-2.4,2-4,0-.4.1-.9.4-1.2l3.1-3.1c.1.4.3.8.7,1.2l6.9,6.9c1.3,1.3,3.5,1.3,4.8,0s1.3-3.5,0-4.8l-7.3-7.3h0ZM15.6,26.2c-.6.6-.9,1.4-.9,2.2,0,1.3-.6,2.4-1.8,3-1.2.6-2.5.5-3.5-.3-.7-.5-1.1-1.3-1.2-2.2s.1-1.7.7-2.4c.6-.8,1.6-1.2,2.6-1.2h.1c.8,0,1.6-.3,2.2-.9l9.2-9.2c.5-.5.7-1.2.6-2-.5-2.2,1-4.4,3.2-4.9.1,0,.3,0,.5,0l-1,1c-.3.3-.5.8-.5,1.3l.2,2c0,.8.7,1.4,1.5,1.5l2,.2c.5,0,1-.1,1.3-.5l1-1c-.2,2-1.8,3.6-3.9,3.8-.4,0-.8,0-1.1,0-.7-.2-1.4,0-2,.6l-8.8,8.8h0s-.4.4-.4.4h0ZM17.9,18.3l-6.5-6.6h0c-.3-.3-.8-.5-1.3-.6-.1,0-.3,0-.4-.1-.2,0-.3-.2-.4-.3l-1.1-2,.2-.2,2,1.1c.1,0,.3.2.3.4,0,.1,0,.2.1.4.2.5.4,1.1.7,1.4l6.5,6.4-.3.3h0ZM22.8,21.1h.2c.5,0,1,0,1.3.4l6.9,6.9c.8.8.8,2,0,2.8s-2,.8-2.8,0l-6.9-6.9c-.3-.3-.3-.8-.4-1.3v-.2s1.7-1.7,1.7-1.7Z\"><\/path><\/svg>                                 <\/span>\r\n                            \r\n                            <span class=\"taxonomy-grid__label\">\r\n                                Heimwerkerm\u00e4rkte                            <\/span>\r\n                        <\/a>\r\n\r\n                    \r\n                        <a class=\"taxonomy-grid__item term-id-490\"                          \r\n                           data-branche-master-id=\"490\"\r\n                           data-branche-master-slug=\"nahrungsmittelherstellung\">\r\n\r\n                                                            <span class=\"taxonomy-grid__icon\">\r\n                                    <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" width=\"40\" height=\"40\" version=\"1.1\" viewBox=\"0 0 40 40\"><defs><style> .cls-1 { fill: #013064; stroke-width: 0px; } <\/style><\/defs><path class=\"cls-1 taxonomy-grid__icon-svg\" d=\"M30.1,24.5c-.8-1.8-2.1-3.3-3.7-4.4-1.6-1.1-3.6-1.7-5.5-1.7h0c-.5,0-1,.4-1,1s.4,1,1,1c1.6,0,3.2.5,4.5,1.4,1.3.9,2.4,2.1,3,3.5.2.4.5.6.9.6s.3,0,.4,0c.5-.2.7-.8.5-1.3h0Z\"><\/path><path class=\"cls-1\" d=\"M38,28.5h-2.6c-.2-3.6-1.8-7-4.5-9.6-2.1-2.1-4.8-3.5-7.7-4.1.4-.6.6-1.2.6-1.9s-.4-1.9-1.1-2.6c-1.2-1.2-3.2-1.4-4.6-.4-.6.4-1.1.9-1.4,1.6s-.4,1.4-.2,2.1c0,.4.3.8.5,1.2-2.9.6-5.6,2-7.7,4-2.7,2.6-4.2,6-4.5,9.6h-2.7c-.5,0-1,.5-1,1s.5,1,1,1h35.9c.5,0,1-.5,1-1s-.5-1-1-1ZM18.5,12.4c.1-.3.3-.5.6-.7s.6-.3.9-.3.9.2,1.2.5c.3.3.5.7.5,1.1s0,.6-.3.9c-.2.3-.4.5-.8.6s-.6.2-1,0c-.3,0-.6-.2-.9-.4-.2-.2-.4-.5-.5-.8,0-.3,0-.6,0-.9h0ZM10.6,20.4c2.5-2.4,5.9-3.8,9.4-3.8h0c3.6,0,6.9,1.4,9.5,3.8,2.3,2.2,3.6,5.1,3.8,8.1H6.7c.2-3.1,1.6-5.9,3.9-8.1Z\"><\/path><\/svg>                                 <\/span>\r\n                            \r\n                            <span class=\"taxonomy-grid__label\">\r\n                                Nahrungsmittelherstellung                            <\/span>\r\n                        <\/a>\r\n\r\n                                    <\/div>\r\n            <\/div>\r\n\r\n            \r\n            \n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-a4208ced\"><div class=\"gb-container gb-container-a4208ced\" data-aos=\"fade-right\">\n<div class=\"gb-container gb-container-29289ffa\">\n\n<p class=\"wp-block-paragraph\"><strong>Maghreb Automation Offshore<\/strong><br>Sig.ra Lamiae Alami<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zone Franche d\u2019Exportation Ilot n. 9, Lot n. 2<br>90.000 Tangeri <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marocco<\/p>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Tel.<\/strong> <a href=\"tel:+2126%2061%2066%2085%2048\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">+2126 61 66 85 48<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>E-mail:<\/strong> <a href=\"mailto:contact@ma-sarl.co\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">contact@ma-sarl.co<\/a><\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>\n\n<section class=\"gb-container gb-container-75738a47 test2222222 gb-container-brand-full\">\n<div class=\"gb-container gb-container-b298f242\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-690c9c2d\">\n<div class=\"gb-grid-column gb-grid-column-39c82c21\"><div class=\"gb-container gb-container-39c82c21\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:var(--global-color-5)\">LUTZ BLADES \u2013 OPERATIVI IN TUTTO IL MONDO<\/h2><\/div>\n\n\n\n<p class=\"has-global-color-5-color has-text-color has-link-color wp-elements-15d56b141228ff150fab5a4321324310 wp-block-paragraph\">Dall&#8217;Europa all&#8217;Asia fino al Medio Oriente, siamo presenti alle fiere pi\u00f9 importanti del mondo, dove presentiamo le nostre lame pi\u00f9 recenti e discutiamo con esperti sul futuro della tecnologia di taglio.<\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-db9a589c\"><div class=\"gb-container gb-container-db9a589c grid-partner-wrapper\">\n\n  \n\n\t\t\t\t\t\t\t\t\t\n            <div class=\"grid grid-1e8493ed grid-fair grid-columns-3\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-group grid-group-0\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-inner  facetwp-template \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t\t\t \n\t\t\t<a target=\"_blank\" href=\"https:\/\/www.medica.de\" class=\"card card-fair card-fair-73969\" rel=\"nofollow\">\n\t\t\t\t<div class=\"card-media\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"270\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/messe_logo_medica.jpg\" class=\"attachment-fair size-fair\" alt=\"\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/messe_logo_medica.jpg 360w, https:\/\/lutz-blades.com\/wp-content\/uploads\/messe_logo_medica-300x225.jpg 300w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/div>\t\t\t\t<div class=\"card-content\">\n\t\t\t\t\t<div class=\"card-inner\">\n\t\t\t\t\t\t<span class=\"card-headline headline is-h3\">Medica 2026<\/span><div class=\"card-copy\"><div class=\"fair-date\">16. &#8211; 19.11.2026<\/div><div class=\"fair-location\">D\u00fcsseldorf \u2013 Padiglione 3 \/ Stand D 71<\/div><\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t\t\t \n\t\t\t<a target=\"_blank\" href=\"https:\/\/www.worldhealthexpo.com\" class=\"card card-fair card-fair-73981\" rel=\"nofollow\">\n\t\t\t\t<div class=\"card-media\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"255\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/whx-labs-dubai-neon-logo-rgb-compressed.png\" class=\"attachment-fair size-fair\" alt=\"\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/whx-labs-dubai-neon-logo-rgb-compressed.png 600w, https:\/\/lutz-blades.com\/wp-content\/uploads\/whx-labs-dubai-neon-logo-rgb-compressed-300x128.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>\t\t\t\t<div class=\"card-content\">\n\t\t\t\t\t<div class=\"card-inner\">\n\t\t\t\t\t\t<span class=\"card-headline headline is-h3\">WHX Dubai 2027<\/span><div class=\"card-copy\"><div class=\"fair-date\">25. &#8211; 28.01.2027<\/div><div class=\"fair-location\">Medio Oriente, Dubai<\/div><\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t\t\t \n\t\t\t<a target=\"_blank\" href=\"https:\/\/itma.com\" class=\"card card-fair card-fair-137860\" rel=\"nofollow\">\n\t\t\t\t<div class=\"card-media\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/ITMA-3-720x540.png\" class=\"attachment-fair size-fair\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"card-content\">\n\t\t\t\t\t<div class=\"card-inner\">\n\t\t\t\t\t\t<span class=\"card-headline headline is-h3\">ITMA 2027<\/span><div class=\"card-copy\"><div class=\"fair-date\">16. &#8211; 22.09.2027<\/div><div class=\"fair-location\">Hannover <\/div><\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t            <\/div>\n\t\t\t\n\t\t\t<!-- if no posts and category \"studenten (36)\" -->\n\t\t\t\t\t\t\t\n\t\t\t\n            <!-- end:grid -->\n        \n            \n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>\n\n<section class=\"gb-container gb-container-1049d57a gb-container-white\">\n<div class=\"gb-container gb-container-6b52727c\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:var(--color-brand)\">Highlight di Prodotto<\/h2><\/div>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-4cd4bdb3 standorte-wrapper marken-grid-wrapper\">\n<div class=\"gb-grid-column gb-grid-column-b5e4cbb2\"><div class=\"gb-container gb-container-b5e4cbb2 marathon-section-item\" data-aos=\"zoom-in\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:var(--global-color-5)\">Marathon<\/h2><span class=\"subheadline\" style=\"color:\">Duro, resistente, duraturo<\/span><\/div>\n\n\n<div class=\"gb-container gb-container-d8c98314 marathon-video\">\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" autoplay loop muted src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/marathon-background-video.mp4\" playsinline><\/video><\/figure>\n\n<\/div>\n\n\n<a class=\"gb-button gb-button-03752b92 gb-button-text gb-button-orange\" href=\"https:\/\/lutz-blades.com\/it\/maratona\/\" target=\"_blank\" rel=\"noopener noreferrer\">Visualizza i prodotti<\/a>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2981\" height=\"2495\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/AdobeStock_329272814_Person-Freigestellt-2.png\" alt=\"\" class=\"wp-image-61021\" style=\"width:960px\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/AdobeStock_329272814_Person-Freigestellt-2.png 2981w, https:\/\/lutz-blades.com\/wp-content\/uploads\/AdobeStock_329272814_Person-Freigestellt-2-300x251.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/AdobeStock_329272814_Person-Freigestellt-2-1024x857.png 1024w, https:\/\/lutz-blades.com\/wp-content\/uploads\/AdobeStock_329272814_Person-Freigestellt-2-768x643.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/AdobeStock_329272814_Person-Freigestellt-2-1536x1286.png 1536w, https:\/\/lutz-blades.com\/wp-content\/uploads\/AdobeStock_329272814_Person-Freigestellt-2-2048x1714.png 2048w, https:\/\/lutz-blades.com\/wp-content\/uploads\/AdobeStock_329272814_Person-Freigestellt-2-597x500.png 597w\" sizes=\"auto, (max-width: 2981px) 100vw, 2981px\" \/><\/figure>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-943e2e82\"><div class=\"gb-container gb-container-943e2e82\" data-aos=\"zoom-in\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left subheadline-gelbgruenn\"><h2 class=\"headline\" style=\"color:var(--global-color-5)\">DERICUT<\/h2><span class=\"subheadline\" style=\"color:\">La nuova lama per scarnitura<\/span><\/div>\n\n\n\n<a class=\"gb-button gb-button-2be62336 gb-button-text gb-button-orange\" href=\"https:\/\/lutz-blades.com\/it\/dericut\/\" target=\"_blank\" rel=\"noopener noreferrer\">SUL PRODOTTO<\/a>\n\n\n\n<figure class=\"gb-block-image gb-block-image-0ce6aa4a\"><img loading=\"lazy\" decoding=\"async\" width=\"762\" height=\"616\" class=\"gb-image gb-image-0ce6aa4a\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/dericut-bg2.jpg\" alt=\"\"  srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/dericut-bg2.jpg 762w, https:\/\/lutz-blades.com\/wp-content\/uploads\/dericut-bg2-300x243.jpg 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/dericut-bg2-619x500.jpg 619w\" sizes=\"auto, (max-width: 762px) 100vw, 762px\" \/><\/figure>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-1e6ad9e3\"><div class=\"gb-container gb-container-1e6ad9e3\" data-aos=\"zoom-in\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left subheadline-blau\"><h2 class=\"headline\" style=\"color:var(--global-color-5)\">Carapaxx<\/h2><span class=\"subheadline\" style=\"color:\">Rivestito da Lutz bLades<\/span><\/div>\n\n\n\n<a class=\"gb-button gb-button-14101037 gb-button-text gb-button-blau\" href=\"https:\/\/lutz-blades.com\/it\/carapaxx\/\" target=\"_blank\" rel=\"noopener noreferrer\">SCOPRI DI PI\u00d9<\/a>\n\n\n\n<figure class=\"gb-block-image gb-block-image-2c253af2\"><img loading=\"lazy\" decoding=\"async\" width=\"762\" height=\"616\" class=\"gb-image gb-image-2c253af2\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/carapaxx-bg.jpg\" alt=\"\"  srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/carapaxx-bg.jpg 762w, https:\/\/lutz-blades.com\/wp-content\/uploads\/carapaxx-bg-300x243.jpg 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/carapaxx-bg-619x500.jpg 619w\" sizes=\"auto, (max-width: 762px) 100vw, 762px\" \/><\/figure>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-07141ec4\"><div class=\"gb-container gb-container-07141ec4\" data-aos=\"zoom-in\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:var(--global-color-5)\">Lynxera<\/h2><span class=\"subheadline\" style=\"color:\">Naturalmente superiore<\/span><\/div>\n\n\n\n<a class=\"gb-button gb-button-e5bdf53a gb-button-text gb-button-orange\" href=\"https:\/\/lutz-blades.com\/mikrotomklingen\/it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Scopri i prodotti<\/a>\n\n\n\n<figure class=\"gb-block-image gb-block-image-2c421b9d\"><img loading=\"lazy\" decoding=\"async\" width=\"762\" height=\"616\" class=\"gb-image gb-image-2c421b9d\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lynxera-bg.jpg\" alt=\"\"  srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lynxera-bg.jpg 762w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lynxera-bg-300x243.jpg 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lynxera-bg-619x500.jpg 619w\" sizes=\"auto, (max-width: 762px) 100vw, 762px\" \/><\/figure>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>\n\n<section class=\"gb-container gb-container-6ddfaeee gb-container-white\">\n<div class=\"gb-container gb-container-2c96b2a2\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-ec4da04c\">\n<div class=\"gb-grid-column gb-grid-column-bcc8faa2\"><div class=\"gb-container gb-container-bcc8faa2\" data-aos=\"fade-right\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h1 class=\"headline is-h2\" style=\"color:\">LUTZ BLADES: Una lama che ispira fiducia<\/h1><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Da oltre 100 anni, il nome LUTZ BLADES \u00e8 sinonimo di qualit\u00e0 e precisione. Ci\u00f2 che ci contraddistingue sono lame che non solo tagliano, ma che, in quanto strumenti industriali, soddisfano in modo affidabile, duraturo e preciso le esigenze dei nostri clienti a livello globale. Sia nell&#8217;industria, nella tecnologia medicale, nel commercio di utensili o nella produzione alimentare, le lame LUTZ BLADES sono la scelta preferita ovunque la precisione sia cruciale.  <\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>\n\n<section class=\"gb-container gb-container-4729574d gb-container-grau\">\n<div class=\"gb-container gb-container-f906c5d1\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-fc8ef450 count-up-raster\">\n<div class=\"gb-grid-column gb-grid-column-8b68c5ae\"><div class=\"gb-container gb-container-8b68c5ae\" data-aos=\"zoom-in\">\n\r\n\t\t\t<!-- start:count-up | Hook: 'px_count-up_before' -->       \r\n            \r\n            <div class=\"count-up count-up-15af01c8\">\r\n\r\n\t\t\t\t<span id=\"count_up_15af01c8\" class=\"count-up-number\">0<\/span><span class=\"count-up-headline\">Lame all&#8217;anno<\/span>\t\t\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t<!-- end:count-up | Hook: 'px_count-up_after' -->\r\n\t\t\t        \r\n            \n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-c1aa4477\"><div class=\"gb-container gb-container-c1aa4477\" data-aos=\"zoom-in\">\n\r\n\t\t\t<!-- start:count-up | Hook: 'px_count-up_before' -->       \r\n            \r\n            <div class=\"count-up count-up-6ed45bee\">\r\n\r\n\t\t\t\t<span id=\"count_up_6ed45bee\" class=\"count-up-number\">0<\/span><span class=\"count-up-headline\">Articoli standard<\/span>\t\t\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t<!-- end:count-up | Hook: 'px_count-up_after' -->\r\n\t\t\t        \r\n            \n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-cbe5a4a1\"><div class=\"gb-container gb-container-cbe5a4a1\" data-aos=\"zoom-in\">\n\r\n\t\t\t<!-- start:count-up | Hook: 'px_count-up_before' -->       \r\n            \r\n            <div class=\"count-up count-up-3fdc4e9d\">\r\n\r\n\t\t\t\t<span id=\"count_up_3fdc4e9d\" class=\"count-up-number\">0<\/span><span class=\"count-up-headline\">Anni di esperienza con le lame<\/span>\t\t\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t<!-- end:count-up | Hook: 'px_count-up_after' -->\r\n\t\t\t        \r\n            \n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-2dba8571\"><div class=\"gb-container gb-container-2dba8571\" data-aos=\"zoom-in\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Qualit\u00e0 tedesca<\/h3><span class=\"subheadline\" style=\"color:\">Qualit\u00e0 su cui fare affidamento<\/span><\/div>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Precise, durevoli e su misura per le tue esigenze: da oltre 100 anni LUTZ BLADES produce lame industriali per applicazioni di taglio meccanico. I nostri oltre 400 dipendenti realizzano soluzioni complete per i clienti nei nostri siti produttivi europei di Solingen (Germania) e Nysa (Polonia), dalla lama fino alla progettazione di dispenser e imballaggi. Da &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Marocco\" class=\"read-more button\" href=\"https:\/\/lutz-blades.com\/it\/partner\/marocco\/#more-108308\" aria-label=\"Per saperne di pi\u00f9 su Marocco\">weiterlesen<\/a><\/p>\n","protected":false},"featured_media":0,"template":"","tx_region":[1173],"class_list":["post-108308","partner","type-partner","status-publish","hentry","tx_region-mittel-nord-afrika","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Partner in Marocco | Lame industriali | LUTZ BLADES<\/title>\n<meta name=\"description\" content=\"Trova il tuo partner LUTZ BLADES in Marocco. Lame industriali ad alta precisione per film, tessile e applicazioni medicali. Qualit\u00e0 tedesca certificata.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lutz-blades.com\/it\/partner\/marocco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partner in Marocco | Lame industriali | LUTZ BLADES\" \/>\n<meta property=\"og:description\" content=\"Trova il tuo partner LUTZ BLADES in Marocco. Lame industriali ad alta precisione per film, tessile e applicazioni medicali. Qualit\u00e0 tedesca certificata.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lutz-blades.com\/it\/partner\/marocco\/\" \/>\n<meta property=\"og:site_name\" content=\"LUTZ BLADES exactly\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-19T08:59:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/LutzBlades_24_106-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/partner\\\/marocco\\\/\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/partner\\\/marocco\\\/\",\"name\":\"Partner in Marocco | Lame industriali | LUTZ BLADES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/partner\\\/marocco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/partner\\\/marocco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/LutzBlades_24_106-1.jpg\",\"datePublished\":\"2025-12-03T08:41:24+00:00\",\"dateModified\":\"2026-05-19T08:59:48+00:00\",\"description\":\"Trova il tuo partner LUTZ BLADES in Marocco. Lame industriali ad alta precisione per film, tessile e applicazioni medicali. Qualit\u00e0 tedesca certificata.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/partner\\\/marocco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lutz-blades.com\\\/it\\\/partner\\\/marocco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/partner\\\/marocco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/LutzBlades_24_106-1.jpg\",\"contentUrl\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/LutzBlades_24_106-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/partner\\\/marocco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marocco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/\",\"name\":\"LUTZ BLADES exactly\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/#organization\",\"name\":\"LUTZ BLADES exactly\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/lutz-blades-logo.svg\",\"contentUrl\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/lutz-blades-logo.svg\",\"width\":240,\"height\":66,\"caption\":\"LUTZ BLADES exactly\"},\"image\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Partner in Marocco | Lame industriali | LUTZ BLADES","description":"Trova il tuo partner LUTZ BLADES in Marocco. Lame industriali ad alta precisione per film, tessile e applicazioni medicali. Qualit\u00e0 tedesca certificata.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lutz-blades.com\/it\/partner\/marocco\/","og_locale":"it_IT","og_type":"article","og_title":"Partner in Marocco | Lame industriali | LUTZ BLADES","og_description":"Trova il tuo partner LUTZ BLADES in Marocco. Lame industriali ad alta precisione per film, tessile e applicazioni medicali. Qualit\u00e0 tedesca certificata.","og_url":"https:\/\/lutz-blades.com\/it\/partner\/marocco\/","og_site_name":"LUTZ BLADES exactly","article_modified_time":"2026-05-19T08:59:48+00:00","og_image":[{"url":"https:\/\/lutz-blades.com\/wp-content\/uploads\/LutzBlades_24_106-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lutz-blades.com\/it\/partner\/marocco\/","url":"https:\/\/lutz-blades.com\/it\/partner\/marocco\/","name":"Partner in Marocco | Lame industriali | LUTZ BLADES","isPartOf":{"@id":"https:\/\/lutz-blades.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lutz-blades.com\/it\/partner\/marocco\/#primaryimage"},"image":{"@id":"https:\/\/lutz-blades.com\/it\/partner\/marocco\/#primaryimage"},"thumbnailUrl":"https:\/\/lutz-blades.com\/wp-content\/uploads\/LutzBlades_24_106-1.jpg","datePublished":"2025-12-03T08:41:24+00:00","dateModified":"2026-05-19T08:59:48+00:00","description":"Trova il tuo partner LUTZ BLADES in Marocco. Lame industriali ad alta precisione per film, tessile e applicazioni medicali. Qualit\u00e0 tedesca certificata.","breadcrumb":{"@id":"https:\/\/lutz-blades.com\/it\/partner\/marocco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lutz-blades.com\/it\/partner\/marocco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lutz-blades.com\/it\/partner\/marocco\/#primaryimage","url":"https:\/\/lutz-blades.com\/wp-content\/uploads\/LutzBlades_24_106-1.jpg","contentUrl":"https:\/\/lutz-blades.com\/wp-content\/uploads\/LutzBlades_24_106-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/lutz-blades.com\/it\/partner\/marocco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/lutz-blades.com\/it\/"},{"@type":"ListItem","position":2,"name":"Marocco"}]},{"@type":"WebSite","@id":"https:\/\/lutz-blades.com\/it\/#website","url":"https:\/\/lutz-blades.com\/it\/","name":"LUTZ BLADES exactly","description":"","publisher":{"@id":"https:\/\/lutz-blades.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lutz-blades.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/lutz-blades.com\/it\/#organization","name":"LUTZ BLADES exactly","url":"https:\/\/lutz-blades.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lutz-blades.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-logo.svg","contentUrl":"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-logo.svg","width":240,"height":66,"caption":"LUTZ BLADES exactly"},"image":{"@id":"https:\/\/lutz-blades.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lutz-blades.com\/it\/wp-json\/wp\/v2\/partner\/108308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lutz-blades.com\/it\/wp-json\/wp\/v2\/partner"}],"about":[{"href":"https:\/\/lutz-blades.com\/it\/wp-json\/wp\/v2\/types\/partner"}],"version-history":[{"count":4,"href":"https:\/\/lutz-blades.com\/it\/wp-json\/wp\/v2\/partner\/108308\/revisions"}],"predecessor-version":[{"id":118943,"href":"https:\/\/lutz-blades.com\/it\/wp-json\/wp\/v2\/partner\/108308\/revisions\/118943"}],"wp:attachment":[{"href":"https:\/\/lutz-blades.com\/it\/wp-json\/wp\/v2\/media?parent=108308"}],"wp:term":[{"taxonomy":"tx_region","embeddable":true,"href":"https:\/\/lutz-blades.com\/it\/wp-json\/wp\/v2\/tx_region?post=108308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}