{"id":29777,"date":"2023-11-08T13:30:19","date_gmt":"2023-11-08T12:30:19","guid":{"rendered":"https:\/\/lutz-blades.com\/?p=29777"},"modified":"2023-10-27T09:02:30","modified_gmt":"2023-10-27T07:02:30","slug":"entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera","status":"publish","type":"post","link":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/","title":{"rendered":"Entretien avec Alexander Lutz : \u00c0 propos des lames de microtome &amp; de LYNXERA\u00ae."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Attention, nous allons maintenant sortir le chat du sac ! Nos toutes nouvelles lames de microtome LYNXERA\u00ae sont synonymes de puissance, d&rsquo;endurance et surtout de pr\u00e9cision. Tout comme le lynx \u00e0 l&rsquo;\u00e9tat sauvage, dont le nom latin, Lynx, a inspir\u00e9 notre nouveau nom de marque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre directeur Alexander Lutz nous a expliqu\u00e9 dans une interview comment nous voulons conqu\u00e9rir le march\u00e9 des lames de microtome avec LYNXERA\u00ae et quel r\u00f4le jouent la qualit\u00e9 et une disponibilit\u00e9 fiable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Plus de 100 ans d&rsquo;existence pour LUTZ BLADES &#8211; pourquoi vous lancez-vous maintenant sur le march\u00e9 des lames de microtome ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tant que fabricant de lames pour des t\u00e2ches de coupe techniques, la fabrication de lames pour le secteur m\u00e9dical est notre activit\u00e9 quotidienne. Les scalpels sp\u00e9ciaux et de nombreuses lames utilis\u00e9es dans les appareils m\u00e9dicaux proviennent de LUTZ depuis des d\u00e9cennies. Il est donc logique d&rsquo;\u00e9largir le portefeuille de produits \u00e0 la fabrication et \u00e0 la vente de lames de microtome. Depuis 2004, nous sommes certifi\u00e9s selon la norme EN ISO 13485 en tant que responsable potentiel de la mise sur le march\u00e9 de dispositifs m\u00e9dicaux. Notre production et notre organisation sont donc capables depuis longtemps de fabriquer des appareils m\u00e9dicaux. Mais jusqu&rsquo;\u00e0 pr\u00e9sent, ce sont nos clients qui mettaient les produits sur le march\u00e9 ; soit sous leur propre nom, soit avec nos lames comme composant dans les appareils techniques. Avec les lames de LUTZ sous la marque LYNXERA\u00ae, nous \u00e9largissons d\u00e9sormais de mani\u00e8re significative notre offre pour le secteur m\u00e9dical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext1_1200x600-1024x512.png\" alt=\"\" class=\"wp-image-29359\" style=\"width:1120px;height:undefinedpx\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext1_1200x600-1024x512.png 1024w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext1_1200x600-300x150.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext1_1200x600-768x384.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext1_1200x600-800x400.png 800w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext1_1200x600.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quels sont les d\u00e9fis que vous avez identifi\u00e9s sur le march\u00e9 ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les exigences pos\u00e9es aux lames de microtome sont tr\u00e8s \u00e9lev\u00e9es. Nous en sommes conscients. La nettet\u00e9, la dur\u00e9e de vie et l&rsquo;homog\u00e9n\u00e9it\u00e9 de la qualit\u00e9 de fabrication sont, \u00e0 juste titre, ce que les gens recherchent dans les microtomes. Nous voulons y r\u00e9pondre au mieux. En tant que nouvel acteur du march\u00e9, il faut d&rsquo;abord gagner la reconnaissance et la confiance des clients. Dans le monde des affaires d&rsquo;aujourd&rsquo;hui, la notion de partenariat est souvent invoqu\u00e9e, mais pas toujours tenue. Nous r\u00e9pondrons au mieux aux souhaits des clients. Nous voulons \u00eatre partenaires. Nous consid\u00e9rons que nos produits sont arm\u00e9s pour faire face \u00e0 la concurrence et nous souhaitons offrir une v\u00e9ritable valeur ajout\u00e9e \u00e0 nos clients.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comment LUTZ BLADES assure-t-il la disponibilit\u00e9 pour le march\u00e9 allemand et europ\u00e9en ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous sommes une entreprise europ\u00e9enne avec des racines allemandes et une fabrication en Allemagne. Nous sommes install\u00e9s \u00e0 Solingen depuis 101 ans et depuis 1992 &#8211; soit 31 ans &#8211; sur le site de Nysa en Pologne. Les entreprises ont toujours \u00e9t\u00e9 g\u00e9r\u00e9es et d\u00e9velopp\u00e9es de la m\u00eame mani\u00e8re, \u00e0 tous les niveaux, en termes de qualit\u00e9 et d&rsquo;organisation. Les sites de production travaillent main dans la main et, dans le cas pr\u00e9sent, la fabrication des lames de microtome a lieu en Allemagne, sur le site de Solingen, et la confection finale sur le site de Nysa. Notre taux d&rsquo;int\u00e9gration verticale pour le produit Lames de microtome est de 100 %. Aucune \u00e9tape de la production n&rsquo;est sous-trait\u00e9e. Cela signifie que les lames de microtome sont 100 % LUTZ ; nous sommes fabricant, pas distributeur ! M\u00eame les syst\u00e8mes de distribution sont fabriqu\u00e9s en interne. Ainsi, nous proposons \u00e0 nos clients des lames qui ont r\u00e9ellement \u00e9t\u00e9 fabriqu\u00e9es sur place. Et nous savons que nos clients l&rsquo;appr\u00e9cient. Jusqu&rsquo;\u00e0 pr\u00e9sent, les sources d&rsquo;approvisionnement de longues distances se situent principalement en Asie. Et c&rsquo;est cette d\u00e9pendance que nous sommes en train de briser. De nombreux utilisateurs dans les laboratoires r\u00e9agissent en disant : \u00ab\u00a0Enfin &#8230;\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les parts de march\u00e9 pour les lames de microtome sont actuellement clairement r\u00e9parties, comment souhaitez-vous vous \u00e9tablir face \u00e0 la concurrence ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seulement par la qualit\u00e9 ! Mais &#8211; nous fabriquons des lames depuis 101 ans. Notre ambition est d&rsquo;\u00eatre per\u00e7us comme des fabricants d&rsquo;outils. Car une lame est un outil. Un outil de haute pr\u00e9cision, un outil de pr\u00e9cision, un outil de coupe. Et ce qui est tr\u00e8s important pour nous, c&rsquo;est que m\u00eame si des millions de lames destin\u00e9es aux secteurs les plus divers sont mises en route chaque mois par nos soins pour \u00eatre livr\u00e9es \u00e0 nos clients, notre exigence est et reste la m\u00eame : chaque, absolument chaque lame doit faire son travail correctement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le lynx, avec son nom latin Lynx, a inspir\u00e9 le nouveau nom de la marque. Pourquoi avoir choisi cette option ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la nature, le lynx incarne les qualit\u00e9s de PUISSANCE, PR\u00c9CISION, ENDURANCE. Et ce sont exactement les m\u00eames caract\u00e9ristiques que nous associons \u00e0 nos lames de microtome.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vous \u00e9voquez en outre la s\u00e9curit\u00e9 des utilisateurs, qu&rsquo;est-ce que LUTZ BLADES fait de mieux que ses concurrents ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mieux &#8230; c&rsquo;est toujours un sujet d\u00e9licat. Disons plut\u00f4t : quelle est notre offre ? Le mot cl\u00e9 est l&rsquo;\u00e9conomie circulaire. Nous sommes conscients que nous fabriquons un outil \u00e0 usage unique. Il y a des raisons \u00e0 cela et on peut les d\u00e9fendre. L&rsquo;industrie travaille sur le cycle qualifi\u00e9 et nous le faisons aussi. L&rsquo;\u00e9limination des lames de microtome usag\u00e9es ne s&rsquo;improvise pas en raison des contaminations. C&rsquo;est l\u00e0 que l&rsquo;utilisateur et le fournisseur doivent travailler ensemble. Et nous sommes pr\u00eats. \u00c9tape 1 : Chaque distributeur de lames de microtome peut recueillir les lames usag\u00e9es sur sa face inf\u00e9rieure dans un puits d&rsquo;\u00e9limination. Le risque de blessure est ainsi minimis\u00e9. \u00c9tape 2 : Nous avons un bac de rejet pratique pour recevoir les lames avec une fermeture autobloquante avant l&rsquo;\u00e9limination finale. Les lames peuvent y \u00eatre largu\u00e9es d&rsquo;une seule main. C&rsquo;est un gain de temps et de s\u00e9curit\u00e9 &#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext2_1200x600-1024x512.png\" alt=\"\" class=\"wp-image-29369\" style=\"width:1120px;height:undefinedpx\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext2_1200x600-1024x512.png 1024w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext2_1200x600-300x150.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext2_1200x600-768x384.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext2_1200x600-800x400.png 800w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext2_1200x600.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Klingen et Solingen, c&rsquo;est depuis toujours une histoire d&rsquo;amour. Avez-vous pu utiliser l&rsquo;expertise existante pour la fabrication des nouvelles lames de microtome ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien s\u00fbr ! Car c&rsquo;est la base de ce que nous faisons. Notre devise est \u00ab\u00a0Pr\u00e9cision, nettet\u00e9, votre succ\u00e8s\u00a0\u00bb et nous exprimons ainsi ce qui est important pour nous : le succ\u00e8s de nos clients. Nous fabriquons des outils de coupe avec l&rsquo;exigence d&rsquo;une pr\u00e9cision maximale dans les g\u00e9om\u00e9tries de la lame &#8211; pas seulement sur le tranchant &#8211; et le tranchant est l&rsquo;attribut qui d\u00e9termine le succ\u00e8s du produit. Les lames doivent \u00eatre tranchantes et couper. Et ce succ\u00e8s doit \u00eatre celui de nos clients ! Notre succ\u00e8s viendra alors tout seul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En 2020, ils ont d\u00e9m\u00e9nag\u00e9 dans un nouveau b\u00e2timent moderne avec un hall de production de 13.000 m\u00b2 dans la zone industrielle Piepersberg \u00e0 Solingen. Ce d\u00e9m\u00e9nagement a-t-il eu un impact sur l&rsquo;entr\u00e9e sur le march\u00e9 des microtomes ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les lames de microtome sont fabriqu\u00e9es selon des processus automatis\u00e9s. Personne n&rsquo;y va \u00e0 la main avec une lime. Et tous les \u00e9quipements de production sont enti\u00e8rement automatis\u00e9s, \u00e0 toutes les \u00e9tapes de la fabrication. Sinon, les fen\u00eatres de fabrication, certes petites, ne peuvent pas du tout \u00eatre atteintes de mani\u00e8re s\u00fbre pour le processus. Notre nouveau site de production est la base pour que nos installations de fabrication, notre organisation du travail et nos processus soient \u00e0 la pointe de la technologie. Nous sommes fiers d&rsquo;avoir l&rsquo;un des ateliers de fabrication de lames les plus modernes du monde. Notre credo : nous ma\u00eetrisons les processus en toute s\u00e9curit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Avez-vous fait l&rsquo;acquisition de machines sp\u00e9ciales pour la fabrication des fines lames de rabot ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les lames de microtome sont des outils exigeants. Cela n&rsquo;est possible que sur les distributeurs automatiques les plus modernes. Et c&rsquo;est pourquoi nous avons investi dans la technologie et la capacit\u00e9. Sinon, nous ne serions pas comp\u00e9titifs \u00e0 l&rsquo;entr\u00e9e sur le march\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ils pr\u00e9sentent LYNXERA\u00ae comme nouveau produit de la maison LUTZ BLADES au salon COMPAMED de cette ann\u00e9e \u00e0 D\u00fcsseldorf. Qu&rsquo;attendez-vous de ce salon ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le contact personnel et une relation \u00e9troite avec les clients ont toujours \u00e9t\u00e9 importants pour nous. Cela permet d&rsquo;apprendre \u00e0 se conna\u00eetre et de faire le grand \u00e9cart pour les clients. C&rsquo;est pourquoi nous voulons montrer le visage de LYNXERA\u00ae d\u00e8s le d\u00e9but et faire comprendre aux clients que nous sommes l\u00e0 pour eux : Nous sommes l\u00e0 pour vous !<br>Notre monde des affaires a beaucoup chang\u00e9 ces derni\u00e8res ann\u00e9es. Les possibilit\u00e9s de se rencontrer et d&rsquo;\u00e9changer en ligne sont d\u00e9sormais presque illimit\u00e9es et accessibles \u00e0 tous les acteurs du march\u00e9 dans le monde entier. Alors pourquoi aller \u00e0 une foire ? N&rsquo;est-ce pas une pens\u00e9e ancienne ? Non, ce n&rsquo;est pas le cas, car le contact personnel cr\u00e9e la confiance ! Nous le savons tous : Les partenaires que nous avons d\u00e9j\u00e0 rencontr\u00e9s personnellement ; avec eux, on communique diff\u00e9remment. Plus confiant, plus direct, plus personnel. Il en sera de m\u00eame lors du lancement de LYNXERA\u00ae. Chez LUTZ, nous nous r\u00e9jouissons de tous ces nouveaux contacts venus du monde entier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quels sont vos objectifs pour LYNXERA\u00ae ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous sommes pr\u00e9sents sur de nombreux march\u00e9s avec nos produits. Nous fabriquons des lames pour les secteurs les plus divers. Nos lames ont g\u00e9n\u00e9ralement des exigences diff\u00e9rentes selon les applications des clients. Notre objectif est toujours le m\u00eame : r\u00e9pondre aux souhaits des clients. C&rsquo;est la seule fa\u00e7on d&rsquo;obtenir la confiance \u00e0 long terme. Il doit en \u00eatre de m\u00eame avec les lames de microtome LYNXERA\u00ae de LUTZ BLADES. Un outil de qualit\u00e9 sur lequel nos clients peuvent compter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext3_1200x600-1024x512.png\" alt=\"\" class=\"wp-image-29378\" style=\"width:1120px;height:undefinedpx\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext3_1200x600-1024x512.png 1024w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext3_1200x600-300x150.png 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext3_1200x600-768x384.png 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext3_1200x600-800x400.png 800w, https:\/\/lutz-blades.com\/wp-content\/uploads\/blog-interview-alexander-lutz-intext3_1200x600.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-group has-bg-light-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">PR\u00c9SENT\u00c9<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alexander Lutz<\/strong>, ing\u00e9nieur dipl\u00f4m\u00e9 (FH), dirige maintenant la troisi\u00e8me g\u00e9n\u00e9ration de l&rsquo;entreprise familiale fond\u00e9e en 1922.<br><br>Tout petit d\u00e9j\u00e0, Alexander regardait par-dessus l&rsquo;\u00e9paule de son p\u00e8re &#8211; et son enthousiasme ne s&rsquo;est jamais d\u00e9menti. Apr\u00e8s son baccalaur\u00e9at, il a d&rsquo;abord suivi une formation de constructeur de moules en acier, puis des \u00e9tudes d&rsquo;ing\u00e9nieur en technologie des proc\u00e9d\u00e9s \u00e0 l&rsquo;\u00e9cole sup\u00e9rieure de Darmstadt.<br><br>En 1992, Alexander Lutz est entr\u00e9 dans l&rsquo;entreprise traditionnelle de Solingen en tant qu&#8217;employ\u00e9 technique. \u00c0 la mort de son p\u00e8re en 2003, il a repris la responsabilit\u00e9 en tant que directeur et associ\u00e9. L&rsquo;innovation, la croissance et la responsabilit\u00e9 ont marqu\u00e9 l&rsquo;entreprise LUTZ pendant plus d&rsquo;un si\u00e8cle et Alexander Lutz a pos\u00e9 la premi\u00e8re pierre d&rsquo;un avenir prosp\u00e8re avec la construction d&rsquo;un nouveau b\u00e2timent moderne en 2020.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pas encore assez ?<\/strong><br>Lisez maintenant le num\u00e9ro complet de <strong><a href=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz_inside_EN_webansicht.pdf\">LUTZ inside<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Attention, nous allons maintenant sortir le chat du sac ! Nos toutes nouvelles lames de microtome LYNXERA\u00ae sont synonymes de puissance, d&rsquo;endurance et surtout de pr\u00e9cision. Tout comme le lynx \u00e0 l&rsquo;\u00e9tat sauvage, dont le nom latin, Lynx, a inspir\u00e9 notre nouveau nom de marque. Notre directeur Alexander Lutz nous a expliqu\u00e9 dans une interview &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Entretien avec Alexander Lutz : \u00c0 propos des lames de microtome &amp; de LYNXERA\u00ae.\" class=\"read-more button\" href=\"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/#more-29777\" aria-label=\"En savoir plus sur Entretien avec Alexander Lutz : \u00c0 propos des lames de microtome &amp; de LYNXERA\u00ae.\">weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":29324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[816,456,818],"tags":[],"class_list":["post-29777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-generalites","category-inside-fr","category-produits","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le directeur de LUTZ \u00e0 propos des lames de microtome &amp; LYNXERA\u00ae.<\/title>\n<meta name=\"description\" content=\"Interview d&#039;Alexander Lutz : LYNXERA\u00ae - le dernier produit de son entreprise &amp; entr\u00e9e sur le march\u00e9 des lames de microtome. Lire maintenant !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le directeur de LUTZ \u00e0 propos des lames de microtome &amp; LYNXERA\u00ae.\" \/>\n<meta property=\"og:description\" content=\"Interview d&#039;Alexander Lutz : LYNXERA\u00ae - le dernier produit de son entreprise &amp; entr\u00e9e sur le march\u00e9 des lames de microtome. Lire maintenant !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/\" \/>\n<meta property=\"og:site_name\" content=\"LUTZ BLADES exactly\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-08T12:30:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog_interview-alexander-lutz_768x301-150x150.png\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"pixel-admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"pixel-admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/\"},\"author\":{\"name\":\"pixel-admin\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#\\\/schema\\\/person\\\/85d05ae255860e5ce920f7f9a2bd3bcd\"},\"headline\":\"Entretien avec Alexander Lutz : \u00c0 propos des lames de microtome &amp; de LYNXERA\u00ae.\",\"datePublished\":\"2023-11-08T12:30:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/\"},\"wordCount\":1823,\"publisher\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/blog_interview-alexander-lutz_768x301.png\",\"articleSection\":[\"G\u00e9n\u00e9ralit\u00e9s\",\"Inside\",\"Produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/\",\"name\":\"Le directeur de LUTZ \u00e0 propos des lames de microtome & LYNXERA\u00ae.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/blog_interview-alexander-lutz_768x301.png\",\"datePublished\":\"2023-11-08T12:30:19+00:00\",\"description\":\"Interview d'Alexander Lutz : LYNXERA\u00ae - le dernier produit de son entreprise & entr\u00e9e sur le march\u00e9 des lames de microtome. Lire maintenant !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/blog_interview-alexander-lutz_768x301.png\",\"contentUrl\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/blog_interview-alexander-lutz_768x301.png\",\"width\":768,\"height\":301},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entretien avec Alexander Lutz : \u00c0 propos des lames de microtome &amp; de LYNXERA\u00ae.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/\",\"name\":\"LUTZ BLADES exactly\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#organization\",\"name\":\"LUTZ BLADES exactly\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/lutz-blades-logo.svg\",\"contentUrl\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/lutz-blades-logo.svg\",\"width\":240,\"height\":66,\"caption\":\"LUTZ BLADES exactly\"},\"image\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#\\\/schema\\\/person\\\/85d05ae255860e5ce920f7f9a2bd3bcd\",\"name\":\"pixel-admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/785fddc6db887433d212271afce3ed342c0426d8cb3df410021c462d8973cb5e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/785fddc6db887433d212271afce3ed342c0426d8cb3df410021c462d8973cb5e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/785fddc6db887433d212271afce3ed342c0426d8cb3df410021c462d8973cb5e?s=96&d=mm&r=g\",\"caption\":\"pixel-admin\"},\"sameAs\":[\"http:\\\/\\\/lutz-blades.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le directeur de LUTZ \u00e0 propos des lames de microtome & LYNXERA\u00ae.","description":"Interview d'Alexander Lutz : LYNXERA\u00ae - le dernier produit de son entreprise & entr\u00e9e sur le march\u00e9 des lames de microtome. Lire maintenant !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/","og_locale":"fr_FR","og_type":"article","og_title":"Le directeur de LUTZ \u00e0 propos des lames de microtome & LYNXERA\u00ae.","og_description":"Interview d'Alexander Lutz : LYNXERA\u00ae - le dernier produit de son entreprise & entr\u00e9e sur le march\u00e9 des lames de microtome. Lire maintenant !","og_url":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/","og_site_name":"LUTZ BLADES exactly","article_published_time":"2023-11-08T12:30:19+00:00","og_image":[{"width":150,"height":150,"url":"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog_interview-alexander-lutz_768x301-150x150.png","type":"image\/png"}],"author":"pixel-admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"pixel-admin","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/#article","isPartOf":{"@id":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/"},"author":{"name":"pixel-admin","@id":"https:\/\/lutz-blades.com\/fr\/#\/schema\/person\/85d05ae255860e5ce920f7f9a2bd3bcd"},"headline":"Entretien avec Alexander Lutz : \u00c0 propos des lames de microtome &amp; de LYNXERA\u00ae.","datePublished":"2023-11-08T12:30:19+00:00","mainEntityOfPage":{"@id":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/"},"wordCount":1823,"publisher":{"@id":"https:\/\/lutz-blades.com\/fr\/#organization"},"image":{"@id":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/#primaryimage"},"thumbnailUrl":"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog_interview-alexander-lutz_768x301.png","articleSection":["G\u00e9n\u00e9ralit\u00e9s","Inside","Produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/","url":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/","name":"Le directeur de LUTZ \u00e0 propos des lames de microtome & LYNXERA\u00ae.","isPartOf":{"@id":"https:\/\/lutz-blades.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/#primaryimage"},"image":{"@id":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/#primaryimage"},"thumbnailUrl":"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog_interview-alexander-lutz_768x301.png","datePublished":"2023-11-08T12:30:19+00:00","description":"Interview d'Alexander Lutz : LYNXERA\u00ae - le dernier produit de son entreprise & entr\u00e9e sur le march\u00e9 des lames de microtome. Lire maintenant !","breadcrumb":{"@id":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/#primaryimage","url":"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog_interview-alexander-lutz_768x301.png","contentUrl":"https:\/\/lutz-blades.com\/wp-content\/uploads\/blog_interview-alexander-lutz_768x301.png","width":768,"height":301},{"@type":"BreadcrumbList","@id":"https:\/\/lutz-blades.com\/fr\/entretien-avec-alexander-lutz-a-propos-des-lames-de-microtome-de-lynxera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/lutz-blades.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Entretien avec Alexander Lutz : \u00c0 propos des lames de microtome &amp; de LYNXERA\u00ae."}]},{"@type":"WebSite","@id":"https:\/\/lutz-blades.com\/fr\/#website","url":"https:\/\/lutz-blades.com\/fr\/","name":"LUTZ BLADES exactly","description":"","publisher":{"@id":"https:\/\/lutz-blades.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lutz-blades.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lutz-blades.com\/fr\/#organization","name":"LUTZ BLADES exactly","url":"https:\/\/lutz-blades.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lutz-blades.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-logo.svg","contentUrl":"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-logo.svg","width":240,"height":66,"caption":"LUTZ BLADES exactly"},"image":{"@id":"https:\/\/lutz-blades.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lutz-blades.com\/fr\/#\/schema\/person\/85d05ae255860e5ce920f7f9a2bd3bcd","name":"pixel-admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/785fddc6db887433d212271afce3ed342c0426d8cb3df410021c462d8973cb5e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/785fddc6db887433d212271afce3ed342c0426d8cb3df410021c462d8973cb5e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/785fddc6db887433d212271afce3ed342c0426d8cb3df410021c462d8973cb5e?s=96&d=mm&r=g","caption":"pixel-admin"},"sameAs":["http:\/\/lutz-blades.com"]}]}},"_links":{"self":[{"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/posts\/29777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/comments?post=29777"}],"version-history":[{"count":8,"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/posts\/29777\/revisions"}],"predecessor-version":[{"id":31756,"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/posts\/29777\/revisions\/31756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/media\/29324"}],"wp:attachment":[{"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/media?parent=29777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/categories?post=29777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/tags?post=29777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}