{"id":7756,"date":"2023-04-28T09:41:37","date_gmt":"2023-04-28T07:41:37","guid":{"rendered":"https:\/\/wp.lutz-blades.com\/protection-des-donnees\/"},"modified":"2025-06-03T16:37:17","modified_gmt":"2025-06-03T14:37:17","slug":"protection-des-donnees","status":"publish","type":"page","link":"https:\/\/lutz-blades.com\/fr\/protection-des-donnees\/","title":{"rendered":"Protection des donn\u00e9es"},"content":{"rendered":"\n\t\t\t<!-- start:hero | Hook: 'px_hero_before' -->       \n            \n            <div class=\"hero hero-eb2830cc sub\" data-slides=\"1\" data-start=\"0\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\r\n\t\t\t<!-- start:hero-slide | Hook: 'px_hero-slide_before' -->       \r\n                    \r\n            <div class=\"hero-slide hero-slide-5f521b3b is-style-image\">\r\n\t\t\t\t<div class=\"hero-canvas\" data-aos=\"fade-right\">\r\n\t\t\t\t\t<h1 class=\"hero-headline\">Protection des donn\u00e9es<\/h1>\t\t\t\t\t<span class=\"hero-subheadline subheadline\">LUTZ BLADES \u00e0 l&rsquo;int\u00e9rieur<\/span>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"hero-media hero-media-image\" data-aos=\"fade-left\"><img loading=\"lazy\" decoding=\"async\" width=\"1860\" height=\"720\" src=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-standort-solingen.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-standort-solingen.jpg 1860w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-standort-solingen-300x116.jpg 300w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-standort-solingen-1024x396.jpg 1024w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-standort-solingen-768x297.jpg 768w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-standort-solingen-1536x595.jpg 1536w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-standort-solingen-800x310.jpg 800w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-standort-solingen-25x10.jpg 25w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-standort-solingen-40x15.jpg 40w, https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-standort-solingen-50x19.jpg 50w\" sizes=\"auto, (max-width: 1860px) 100vw, 1860px\" \/><\/div>            <\/div>\r\n\t\t\t\t\r\n            <!-- end:hero-slide | Hook: 'px_hero-slide_after' -->\t\t\t\r\n\t\t\t\r\n\r\n\r\n            \n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\n\t\t\t<!-- end:hero-->        \n            \n\n<section class=\"gb-container gb-container-f420d16f gb-container-white\">\n<div class=\"gb-container gb-container-1bb3f6f5\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-20769924\">\n<div class=\"gb-grid-column gb-grid-column-ff356af9\"><div class=\"gb-container gb-container-ff356af9\" data-aos=\"fade-right\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:\">1. la protection des donn\u00e9es en un coup d&rsquo;\u0153il<\/h2><\/div>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Remarques g\u00e9n\u00e9rales<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Les indications suivantes donnent un aper\u00e7u simple de ce qui se passe avec vos donn\u00e9es personnelles lorsque vous visitez ce site web. Les donn\u00e9es personnelles sont toutes les donn\u00e9es qui permettent de vous identifier personnellement. Vous trouverez des informations d\u00e9taill\u00e9es sur le th\u00e8me de la protection des donn\u00e9es dans notre d\u00e9claration de protection des donn\u00e9es mentionn\u00e9e sous ce texte.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Collecte de donn\u00e9es sur ce site web<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Qui est responsable de la collecte des donn\u00e9es sur ce site ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le traitement des donn\u00e9es sur ce site web est effectu\u00e9 par l&rsquo;exploitant du site web. Vous trouverez ses coordonn\u00e9es dans la section \u00ab\u00a0Informations sur le responsable du traitement\u00a0\u00bb de la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Comment recueillons-nous vos donn\u00e9es ?<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Vos donn\u00e9es sont collect\u00e9es, d&rsquo;une part, lorsque vous nous les communiquez. Il peut s&rsquo;agir, par exemple, de donn\u00e9es que vous saisissez dans un formulaire de contact.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D&rsquo;autres donn\u00e9es sont collect\u00e9es automatiquement ou apr\u00e8s votre consentement par nos syst\u00e8mes informatiques lorsque vous visitez le site. Il s&rsquo;agit principalement de donn\u00e9es techniques (par exemple, le navigateur Internet, le syst\u00e8me d&rsquo;exploitation ou l&rsquo;heure de consultation de la page). La collecte de ces donn\u00e9es est automatique d\u00e8s que vous acc\u00e9dez \u00e0 ce site.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">\u00c0 quelles fins utilisons-nous vos donn\u00e9es ?<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Une partie des donn\u00e9es est collect\u00e9e afin de garantir une mise \u00e0 disposition sans erreur du site web. D&rsquo;autres donn\u00e9es peuvent \u00eatre utilis\u00e9es pour analyser votre comportement d&rsquo;utilisateur. La fourniture de vos donn\u00e9es personnelles est n\u00e9cessaire pour pouvoir traiter vos demandes et y r\u00e9pondre. Si vous ne fournissez pas ces donn\u00e9es, il se peut que nous ne puissions pas traiter votre demande ou y r\u00e9pondre. <\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Quels sont vos droits concernant vos donn\u00e9es ?<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Vous avez \u00e0 tout moment le droit d&rsquo;obtenir gratuitement des informations sur l&rsquo;origine, le destinataire et la finalit\u00e9 de vos donn\u00e9es personnelles enregistr\u00e9es. Vous avez \u00e9galement le droit de demander la rectification ou la suppression de ces donn\u00e9es. Si vous avez donn\u00e9 votre consentement au traitement des donn\u00e9es, vous pouvez \u00e0 tout moment r\u00e9voquer ce consentement pour l&rsquo;avenir. Vous avez \u00e9galement le droit, dans certaines circonstances, de demander la limitation du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, vous avez le droit de d\u00e9poser une plainte aupr\u00e8s de l&rsquo;autorit\u00e9 de contr\u00f4le comp\u00e9tente si vous estimez que le traitement de vos donn\u00e9es personnelles enfreint la l\u00e9gislation sur la protection des donn\u00e9es. Vous trouverez de plus amples informations et les coordonn\u00e9es de contact sur le site web de la Commission nationale pour la protection des donn\u00e9es et la s\u00e9curit\u00e9 de l&rsquo;information<a href=\"https:\/\/www.ldi.nrw.de\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">(www.ldi.nrw.de)<\/a>. <\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Outils d&rsquo;analyse et outils de tiers<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous visitez ce site, votre comportement de navigation peut faire l&rsquo;objet d&rsquo;une \u00e9valuation statistique. Cela se fait surtout avec des programmes dits d&rsquo;analyse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous trouverez des informations d\u00e9taill\u00e9es sur ces programmes d&rsquo;analyse dans la d\u00e9claration de confidentialit\u00e9 suivante.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:\">2. l&rsquo;h\u00e9bergement<\/h2><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nous h\u00e9bergeons le contenu de notre site web chez le fournisseur suivant :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>All-Inkl<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le fournisseur est ALL-INKL.COM &#8211; Neue Medien M\u00fcnnich, Inh. Ren\u00e9 M\u00fcnnich, Hauptstra\u00dfe 68, 02742 Friedersdorf (ci-apr\u00e8s d\u00e9nomm\u00e9 All-Inkl). Pour plus de d\u00e9tails, veuillez consulter la d\u00e9claration de confidentialit\u00e9 d&rsquo;All-Inkl <a href=\"https:\/\/all-inkl.com\/datenschutzinformationen\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">: https:\/\/all-inkl.com\/datenschutzinformationen\/.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;utilisation d&rsquo;All-Inkl se fait sur la base de l&rsquo;art. 6 al. 1 lit. f du RGPD. Nous avons un int\u00e9r\u00eat l\u00e9gitime \u00e0 ce que notre site web soit pr\u00e9sent\u00e9 de la mani\u00e8re la plus fiable possible. Dans la mesure o\u00f9 un consentement correspondant a \u00e9t\u00e9 demand\u00e9, le traitement est effectu\u00e9 exclusivement sur la base de l&rsquo;article 6, paragraphe 6. 1 lit. a RGPD et \u00a7 25 al. 1 TDDDG, dans la mesure o\u00f9 le consentement inclut le stockage de cookies ou l&rsquo;acc\u00e8s \u00e0 des informations dans l&rsquo;\u00e9quipement terminal de l&rsquo;utilisateur (par ex. Device-Fingerprinting) au sens de la TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:\">3. indications g\u00e9n\u00e9rales et informations obligatoires<\/h2><\/div>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Protection des donn\u00e9es<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Les exploitants de ces pages prennent la protection de vos donn\u00e9es personnelles tr\u00e8s au s\u00e9rieux. Nous traitons vos donn\u00e9es personnelles de mani\u00e8re confidentielle et conform\u00e9ment aux dispositions l\u00e9gales en mati\u00e8re de protection des donn\u00e9es et \u00e0 la pr\u00e9sente d\u00e9claration de confidentialit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous utilisez ce site web, diverses donn\u00e9es \u00e0 caract\u00e8re personnel sont collect\u00e9es. Les donn\u00e9es personnelles sont des donn\u00e9es qui permettent de vous identifier personnellement. La pr\u00e9sente d\u00e9claration de confidentialit\u00e9 explique quelles donn\u00e9es nous collectons et \u00e0 quelles fins nous les utilisons. Elle explique \u00e9galement comment et dans quel but cela est fait.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous attirons votre attention sur le fait que la transmission de donn\u00e9es sur Internet (par exemple lors de la communication par e-mail) peut pr\u00e9senter des failles de s\u00e9curit\u00e9. Une protection compl\u00e8te des donn\u00e9es contre l&rsquo;acc\u00e8s par des tiers n&rsquo;est pas possible.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Remarque sur le service responsable<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Le responsable du traitement des donn\u00e9es sur ce site est :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LUTZ GmbH &amp; Co KG<br>Piepersberg 20<br>42653 Solingen<br>Allemagne<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">T\u00e9l\u00e9phone : +49 212 5966-0<br>E-mail : <a href=\"mailto:info@lutz-blades.com\"><\/a><a href=\"javascript:linkTo_UnCryptMailto%27ocknvq%%5C%) ;\" target=\"_blank\" rel=\"nofollow\">info@lutz-blades.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le responsable du traitement est la personne physique ou morale qui, seule ou conjointement avec d&rsquo;autres, d\u00e9termine les finalit\u00e9s et les moyens du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel (par exemple, les noms, les adresses \u00e9lectroniques ou autres).<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Dur\u00e9e de stockage<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la mesure o\u00f9 aucune dur\u00e9e de conservation sp\u00e9cifique n&rsquo;est mentionn\u00e9e dans la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es, vos donn\u00e9es \u00e0 caract\u00e8re personnel restent chez nous jusqu&rsquo;\u00e0 ce que la finalit\u00e9 du traitement des donn\u00e9es soit supprim\u00e9e. Si vous faites valoir une demande l\u00e9gitime d&rsquo;effacement ou si vous r\u00e9voquez un consentement au traitement des donn\u00e9es, vos donn\u00e9es seront effac\u00e9es, \u00e0 moins que nous n&rsquo;ayons d&rsquo;autres raisons l\u00e9galement valables de conserver vos donn\u00e9es personnelles (par exemple, des d\u00e9lais de conservation en vertu du droit fiscal ou commercial) ; dans ce dernier cas, l&rsquo;effacement aura lieu apr\u00e8s la disparition de ces raisons.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Informations g\u00e9n\u00e9rales sur les bases juridiques du traitement des donn\u00e9es sur ce site web<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez donn\u00e9 votre consentement au traitement des donn\u00e9es, nous traitons vos donn\u00e9es personnelles sur la base de l&rsquo;article 6, paragraphe 1, de la loi sur la protection des donn\u00e9es. 1 lit. a du RGPD ou de l&rsquo;art. 9, al. 2 lit. a RGPD, dans la mesure o\u00f9 des cat\u00e9gories particuli\u00e8res de donn\u00e9es sont trait\u00e9es conform\u00e9ment \u00e0 l&rsquo;article 9, paragraphe 1, du RGPD. 1 RGPD. En cas de consentement explicite au transfert de donn\u00e9es \u00e0 caract\u00e8re personnel vers des pays tiers, le traitement des donn\u00e9es s&rsquo;effectue en outre sur la base de l&rsquo;article 49, paragraphe 1, de la loi sur la protection des donn\u00e9es. 1 lit. a RGPD. Si vous avez consenti \u00e0 l&rsquo;enregistrement de cookies ou \u00e0 l&rsquo;acc\u00e8s \u00e0 des informations dans votre terminal (par exemple via l&#8217;empreinte digitale de l&rsquo;appareil), le traitement des donn\u00e9es s&rsquo;effectue en outre sur la base de l&rsquo;article 25, paragraphe 1, de la loi sur la protection des donn\u00e9es. 1 TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment. Si vos donn\u00e9es sont n\u00e9cessaires \u00e0 l&rsquo;ex\u00e9cution d&rsquo;un contrat ou \u00e0 la mise en \u0153uvre de mesures pr\u00e9contractuelles, nous traitons vos donn\u00e9es sur la base de l&rsquo;article 6, paragraphe 6. 1 lit. b du RGPD. En outre, nous traitons vos donn\u00e9es dans la mesure o\u00f9 elles sont n\u00e9cessaires au respect d&rsquo;une obligation l\u00e9gale sur la base de l&rsquo;article 6, paragraphe 1, de la loi sur la protection des donn\u00e9es. 1 lit. c du RGPD. Le traitement des donn\u00e9es peut en outre \u00eatre fond\u00e9 sur notre int\u00e9r\u00eat l\u00e9gitime conform\u00e9ment \u00e0 l&rsquo;art. 6, al. 1 lit. f du RGPD. Les paragraphes suivants de la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es informent sur les bases juridiques applicables dans chaque cas.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">D\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons d\u00e9sign\u00e9 un responsable de la protection des donn\u00e9es :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bechtle GmbH IT-Systemhaus Solingen<br>Piepersberg 42<br>42653 Solingen<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">T\u00e9l\u00e9phone : +49 212 5966-0<br>E-mail : <a href=\"mailto:datenschutz@lutz-blades.com\">datenschutz@lutz-blades.com<\/a><\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">R\u00e9vocation de votre consentement au traitement des donn\u00e9es<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">De nombreuses op\u00e9rations de traitement des donn\u00e9es ne sont possibles qu&rsquo;avec votre consentement explicite. Vous pouvez r\u00e9voquer \u00e0 tout moment un consentement d\u00e9j\u00e0 donn\u00e9. La l\u00e9galit\u00e9 du traitement des donn\u00e9es effectu\u00e9 jusqu&rsquo;\u00e0 la r\u00e9vocation n&rsquo;est pas affect\u00e9e par la r\u00e9vocation.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Droit d&rsquo;opposition \u00e0 la collecte de donn\u00e9es dans des cas particuliers ainsi qu&rsquo;\u00e0 la publicit\u00e9 directe (art. 21 RGPD)<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Si le traitement des donn\u00e9es est fond\u00e9 sur l&rsquo;art. 6, al. 1 lit. e ou f du RGPD, ils ont le droit de s&rsquo;opposer \u00e0 tout moment, pour des raisons tenant \u00e0 leur situation particuli\u00e8re, au traitement de leurs donn\u00e9es \u00e0 caract\u00e8re personnel ; cela vaut \u00e9galement pour le profilage fond\u00e9 sur ces dispositions. Vous trouverez dans la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es la base juridique sur laquelle se fonde le traitement. si vous vous y opposez, nous ne traiterons plus vos donn\u00e9es \u00e0 caract\u00e8re personnel concern\u00e9es, \u00e0 moins que nous puissions d\u00e9montrer qu&rsquo;il existe des motifs l\u00e9gitimes et imp\u00e9rieux pour le traitement qui pr\u00e9valent sur vos int\u00e9r\u00eats, vos droits et vos libert\u00e9s, ou que le traitement sert \u00e0 faire valoir, \u00e0 exercer ou \u00e0 d\u00e9fendre des droits en justice (opposition conform\u00e9ment \u00e0 l&rsquo;article 21, paragraphe 1, du RGPD).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si leurs donn\u00e9es personnelles sont trait\u00e9es pour faire de la publicit\u00e9 directe, ils ont le droit de s&rsquo;opposer \u00e0 tout moment au traitement des donn\u00e9es personnelles concern\u00e9es \u00e0 des fins de publicit\u00e9 ; cela s&rsquo;applique \u00e9galement au profilage dans la mesure o\u00f9 il est li\u00e9 \u00e0 cette publicit\u00e9 directe. si vous vous y opposez, vos donn\u00e9es personnelles ne seront ensuite plus utilis\u00e9es \u00e0 des fins de publicit\u00e9 directe (opposition conform\u00e9ment \u00e0 l&rsquo;article 21, paragraphe 2, du RGPD).<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Droit de recours aupr\u00e8s de l&rsquo;autorit\u00e9 de surveillance comp\u00e9tente<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En cas de violation du RGPD, les personnes concern\u00e9es disposent d&rsquo;un droit de recours aupr\u00e8s d&rsquo;une autorit\u00e9 de contr\u00f4le, notamment dans l&rsquo;\u00c9tat membre de leur r\u00e9sidence habituelle, de leur lieu de travail ou du lieu de la violation pr\u00e9sum\u00e9e. Le droit de recours est sans pr\u00e9judice des autres voies de recours administratives ou judiciaires.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Droit \u00e0 la portabilit\u00e9 des donn\u00e9es<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Vous avez le droit de vous faire remettre ou de faire remettre \u00e0 un tiers, dans un format courant et lisible par machine, les donn\u00e9es que nous traitons de mani\u00e8re automatis\u00e9e sur la base de votre consentement ou en ex\u00e9cution d&rsquo;un contrat. Si vous demandez le transfert direct des donn\u00e9es \u00e0 un autre responsable, cela ne se fera que dans la mesure o\u00f9 cela est techniquement faisable.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Acc\u00e8s, suppression et rectification<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cadre des dispositions l\u00e9gales en vigueur, vous avez \u00e0 tout moment le droit d&rsquo;obtenir gratuitement des informations sur vos donn\u00e9es personnelles enregistr\u00e9es, leur origine et leur destinataire ainsi que sur la finalit\u00e9 du traitement des donn\u00e9es et, le cas \u00e9ch\u00e9ant, un droit de rectification ou de suppression de ces donn\u00e9es. Vous pouvez nous contacter \u00e0 tout moment \u00e0 ce sujet ou pour toute autre question concernant les donn\u00e9es personnelles.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Droit \u00e0 la limitation du traitement<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Vous avez le droit de demander la limitation du traitement de vos donn\u00e9es personnelles. Pour ce faire, vous pouvez nous contacter \u00e0 tout moment. Le droit \u00e0 la limitation du traitement s&rsquo;applique dans les cas suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si vous contestez l&rsquo;exactitude des donn\u00e9es personnelles que nous d\u00e9tenons \u00e0 votre sujet, nous avons g\u00e9n\u00e9ralement besoin de temps pour le v\u00e9rifier. Pendant la dur\u00e9e de l&rsquo;examen, vous avez le droit de demander la limitation du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel.<\/li>\n\n\n\n<li>Si le traitement de vos donn\u00e9es personnelles s&rsquo;est produit\/se produit de mani\u00e8re ill\u00e9gale, vous pouvez demander la limitation du traitement des donn\u00e9es au lieu de leur suppression.<\/li>\n\n\n\n<li>Si nous n&rsquo;avons plus besoin de vos donn\u00e9es \u00e0 caract\u00e8re personnel, mais que vous en avez besoin pour exercer, d\u00e9fendre ou faire valoir des droits juridiques, vous avez le droit de demander la limitation du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel au lieu de leur suppression.<\/li>\n\n\n\n<li>Si vous souhaitez faire opposition conform\u00e9ment \u00e0 l&rsquo;article 21, paragraphe 1, de la directive sur la protection des donn\u00e9es, vous pouvez le faire en nous contactant. 1 RGPD, un \u00e9quilibre doit \u00eatre trouv\u00e9 entre vos int\u00e9r\u00eats et les n\u00f4tres. Tant qu&rsquo;il n&rsquo;a pas \u00e9t\u00e9 d\u00e9termin\u00e9 quels int\u00e9r\u00eats pr\u00e9valent, vous avez le droit d&rsquo;exiger la limitation du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez limit\u00e9 le traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel, ces donn\u00e9es &#8211; \u00e0 l&rsquo;exception de leur conservation &#8211; ne peuvent \u00eatre trait\u00e9es qu&rsquo;avec votre consentement ou pour la constatation, l&rsquo;exercice ou la d\u00e9fense de droits en justice ou pour la protection des droits d&rsquo;une autre personne physique ou morale, ou encore pour un motif d&rsquo;int\u00e9r\u00eat public important de l&rsquo;Union europ\u00e9enne ou d&rsquo;un \u00c9tat membre.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Chiffrement SSL ou TLS<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Pour des raisons de s\u00e9curit\u00e9 et pour prot\u00e9ger la transmission de contenus confidentiels, tels que les commandes ou les demandes que vous nous envoyez en tant qu&rsquo;exploitant du site, ce site utilise un cryptage SSL ou TLS. Vous reconnaissez une connexion crypt\u00e9e au fait que la ligne d&rsquo;adresse du navigateur passe de \u00ab\u00a0http:\/\/\u00a0\u00bb \u00e0 \u00ab\u00a0https:\/\/\u00a0\u00bb et au symbole du cadenas dans la ligne de votre navigateur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si le cryptage SSL ou TLS est activ\u00e9, les donn\u00e9es que vous nous transmettez ne peuvent pas \u00eatre lues par des tiers.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:\">4. collecte de donn\u00e9es sur ce site web<\/h2><\/div>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Cookies<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nos pages Internet utilisent ce que l&rsquo;on appelle des \u00ab\u00a0cookies\u00a0\u00bb. Les cookies sont de petits paquets de donn\u00e9es qui ne causent aucun dommage \u00e0 votre terminal. Ils sont enregistr\u00e9s sur votre terminal soit temporairement pour la dur\u00e9e d&rsquo;une session (cookies de session), soit durablement (cookies permanents). Les cookies de session sont automatiquement supprim\u00e9s \u00e0 la fin de votre visite. Les cookies permanents restent enregistr\u00e9s sur votre terminal jusqu&rsquo;\u00e0 ce que vous les supprimiez vous-m\u00eame ou qu&rsquo;une suppression automatique soit effectu\u00e9e par votre navigateur web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des cookies de soci\u00e9t\u00e9s tierces peuvent \u00e9galement \u00eatre partiellement enregistr\u00e9s sur votre terminal lorsque vous acc\u00e9dez \u00e0 notre site (cookies tiers). Ils nous permettent ou vous permettent d&rsquo;utiliser certains services de l&rsquo;entreprise tierce (par exemple, les cookies pour le traitement des services de paiement).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les cookies ont diff\u00e9rentes fonctions. De nombreux cookies sont techniquement n\u00e9cessaires, car certaines fonctions du site web ne fonctionneraient pas sans eux (par exemple la fonction de panier d&rsquo;achat ou l&rsquo;affichage de vid\u00e9os). D&rsquo;autres cookies servent \u00e0 \u00e9valuer le comportement des utilisateurs ou \u00e0 afficher des publicit\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les cookies n\u00e9cessaires \u00e0 l&rsquo;ex\u00e9cution du processus de communication \u00e9lectronique, \u00e0 la mise \u00e0 disposition de certaines fonctions que vous souhaitez (par exemple pour la fonction de panier d&rsquo;achat) ou \u00e0 l&rsquo;optimisation du site web (par exemple les cookies de mesure d&rsquo;audience du web) (cookies n\u00e9cessaires) sont utilis\u00e9s sur la base de l&rsquo;article 6, paragraphe 6, de la loi sur la protection des donn\u00e9es. 1 lit. f du RGPD, sauf si une autre base juridique est indiqu\u00e9e. L&rsquo;exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 l&rsquo;enregistrement des cookies n\u00e9cessaires \u00e0 la mise \u00e0 disposition de ses services sans erreur technique et de mani\u00e8re optimis\u00e9e. Si un consentement a \u00e9t\u00e9 demand\u00e9 pour le stockage de cookies et de technologies de reconnaissance comparables, le traitement est effectu\u00e9 exclusivement sur la base de ce consentement (article 6, paragraphe 1, point a) du RGPD et article 25, paragraphe 1 de la TDDDG) ; le consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez configurer votre navigateur de mani\u00e8re \u00e0 \u00eatre inform\u00e9 de l&rsquo;installation de cookies et \u00e0 n&rsquo;autoriser les cookies qu&rsquo;au cas par cas, \u00e0 exclure l&rsquo;acceptation de cookies dans certains cas ou de mani\u00e8re g\u00e9n\u00e9rale, et \u00e0 activer la suppression automatique des cookies \u00e0 la fermeture du navigateur. Si les cookies sont d\u00e9sactiv\u00e9s, la fonctionnalit\u00e9 de ce site web peut \u00eatre limit\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si des cookies sont utilis\u00e9s par des entreprises tierces ou \u00e0 des fins d&rsquo;analyse, nous vous en informerons s\u00e9par\u00e9ment dans le cadre de la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es et, le cas \u00e9ch\u00e9ant, nous vous demanderons votre consentement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<span class=\"borlabs-cookie-open-dialog-preferences \" data-borlabs-cookie-title=\"Ouvrir pr\u00e9f\u00e9rences en mati\u00e8re de consentement\" data-borlabs-cookie-type=\"link\" ><\/span>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Fichiers journaux du serveur<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Le fournisseur des pages collecte et enregistre automatiquement des informations dans ce que l&rsquo;on appelle des fichiers journaux du serveur, que votre navigateur nous transmet automatiquement. Il s&rsquo;agit de<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Type et version du navigateur<\/li>\n\n\n\n<li>le syst\u00e8me d&rsquo;exploitation utilis\u00e9<\/li>\n\n\n\n<li>URL du r\u00e9f\u00e9rent<\/li>\n\n\n\n<li>nom d&rsquo;h\u00f4te de l&rsquo;ordinateur qui acc\u00e8de au site<\/li>\n\n\n\n<li>Heure de la demande du serveur<\/li>\n\n\n\n<li>Adresse IP<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ces donn\u00e9es ne sont pas recoup\u00e9es avec d&rsquo;autres sources de donn\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La collecte de ces donn\u00e9es s&rsquo;effectue sur la base de l&rsquo;art. 6 al. 1 lit. f du RGPD. L&rsquo;exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 ce que son site web soit pr\u00e9sent\u00e9 sans erreur technique et \u00e0 ce qu&rsquo;il soit optimis\u00e9 &#8211; pour cela, les fichiers journaux du serveur doivent \u00eatre saisis.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Formulaire de contact<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous nous faites parvenir des demandes par le biais du formulaire de contact, les informations que vous avez fournies dans le formulaire de demande, y compris les donn\u00e9es de contact que vous y avez indiqu\u00e9es, sont enregistr\u00e9es chez nous \u00e0 des fins de traitement de la demande et en cas de questions de suivi. Nous ne transmettons pas ces donn\u00e9es sans votre consentement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le traitement de ces donn\u00e9es s&rsquo;effectue sur la base de l&rsquo;art. 6 al. 1 lit. b RGPD, dans la mesure o\u00f9 votre demande est li\u00e9e \u00e0 l&rsquo;ex\u00e9cution d&rsquo;un contrat ou est n\u00e9cessaire \u00e0 l&rsquo;ex\u00e9cution de mesures pr\u00e9contractuelles. Dans tous les autres cas, le traitement repose sur notre int\u00e9r\u00eat l\u00e9gitime \u00e0 traiter efficacement les demandes qui nous sont adress\u00e9es (article 6, paragraphe 1, point f) du RGPD) ou sur votre consentement (article 6, paragraphe 1, point a) du RGPD), dans la mesure o\u00f9 celui-ci a \u00e9t\u00e9 demand\u00e9 ; le consentement peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es que vous avez saisies dans le formulaire de contact restent chez nous jusqu&rsquo;\u00e0 ce que vous nous demandiez de les supprimer, que vous r\u00e9voquiez votre consentement \u00e0 leur stockage ou que le but du stockage des donn\u00e9es devienne caduc (par exemple, une fois que votre demande a \u00e9t\u00e9 trait\u00e9e). Les dispositions l\u00e9gales contraignantes &#8211; notamment les d\u00e9lais de conservation &#8211; ne sont pas affect\u00e9es.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Bulletin d&rsquo;information<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Donn\u00e9es de la newsletter<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez recevoir la newsletter propos\u00e9e sur le site, nous avons besoin d&rsquo;une adresse e-mail et d&rsquo;informations nous permettant de v\u00e9rifier que vous \u00eates bien le propri\u00e9taire de l&rsquo;adresse e-mail indiqu\u00e9e et que vous acceptez de recevoir la newsletter. Nous ne collectons pas d&rsquo;autres donn\u00e9es ou alors uniquement sur une base volontaire. Vous pouvez \u00e0 tout moment vous opposer \u00e0 l&rsquo;utilisation sp\u00e9cifique de vos donn\u00e9es. Pour le traitement de la newsletter, nous faisons appel \u00e0 des fournisseurs de services de newsletter, d\u00e9crits ci-dessous.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Brevo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce site utilise Brevo pour l&rsquo;envoi de newsletters. Le fournisseur est Sendinblue GmbH, K\u00f6penicker Stra\u00dfe 126, 10179 Berlin, Allemagne. Brevo est un service qui permet, entre autres, d&rsquo;organiser et d&rsquo;analyser l&rsquo;envoi de newsletters. Les donn\u00e9es que vous avez saisies dans le but de vous abonner \u00e0 la newsletter sont stock\u00e9es sur les serveurs de Sendinblue GmbH en Allemagne.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Analyse des donn\u00e9es par Brevo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brevo nous permet d&rsquo;analyser nos campagnes de newsletter. Par exemple, nous pouvons voir si un message de newsletter a \u00e9t\u00e9 ouvert et, le cas \u00e9ch\u00e9ant, quels liens ont \u00e9t\u00e9 cliqu\u00e9s. De cette mani\u00e8re, nous pouvons notamment d\u00e9terminer quels liens ont \u00e9t\u00e9 particuli\u00e8rement cliqu\u00e9s.<br>Nous pouvons \u00e9galement savoir si certaines actions pr\u00e9d\u00e9finies ont \u00e9t\u00e9 effectu\u00e9es apr\u00e8s l&rsquo;ouverture\/le clic (taux de conversion). Nous pouvons ainsi savoir, par exemple, si vous avez effectu\u00e9 un achat apr\u00e8s avoir cliqu\u00e9 sur la newsletter. Brevo nous permet \u00e9galement de classer les destinataires de la newsletter en fonction de diff\u00e9rentes cat\u00e9gories (\u00ab\u00a0clusters\u00a0\u00bb). Les destinataires de la newsletter peuvent par exemple \u00eatre class\u00e9s par \u00e2ge, sexe ou lieu de r\u00e9sidence. De cette mani\u00e8re, les newsletters peuvent \u00eatre mieux adapt\u00e9es aux diff\u00e9rents groupes cibles. Si vous ne souhaitez pas que Brevo proc\u00e8de \u00e0 une analyse, vous devez vous d\u00e9sabonner de la newsletter. Pour cela, nous mettons \u00e0 disposition un lien correspondant dans chaque message de la newsletter. Pour plus d&rsquo;informations sur les fonctionnalit\u00e9s de Brevo, cliquez sur le lien suivant : <a href=\"https:\/\/www.brevo.com\/de\/newsletter-software\/\" target=\"_blank\" rel=\"nofollow\">https:\/\/www.brevo.com\/de\/newsletter-software\/.<\/a>         <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Base juridique<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le traitement des donn\u00e9es est bas\u00e9 sur votre consentement (article 6, paragraphe 1, point a) du RGPD). Vous pouvez r\u00e9voquer ce consentement \u00e0 tout moment. La l\u00e9galit\u00e9 des op\u00e9rations de traitement des donn\u00e9es d\u00e9j\u00e0 effectu\u00e9es n&rsquo;est pas affect\u00e9e par la r\u00e9vocation.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dur\u00e9e de stockage<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es que vous nous avez fournies pour vous abonner \u00e0 la newsletter seront conserv\u00e9es par nous ou par le fournisseur de services de newsletter<br>jusqu&rsquo;\u00e0 ce que vous vous d\u00e9sabonniez de la newsletter et seront supprim\u00e9es de la liste de diffusion de la newsletter une fois que vous vous serez d\u00e9sabonn\u00e9 de la newsletter. Les donn\u00e9es qui ont \u00e9t\u00e9 stock\u00e9es \u00e0 d&rsquo;autres fins chez nous<br>ne sont pas affect\u00e9es.<br>Apr\u00e8s votre d\u00e9sinscription de la liste de distribution de la newsletter, votre adresse e-mail sera \u00e9ventuellement stock\u00e9e dans une liste noire chez nous ou chez le fournisseur de services de newsletter, si cela est n\u00e9cessaire pour emp\u00eacher de futurs mailings. Les donn\u00e9es de la liste noire ne sont utilis\u00e9es qu&rsquo;\u00e0 cette fin et ne sont pas recoup\u00e9es avec d&rsquo;autres donn\u00e9es. Cela sert \u00e0 la fois votre int\u00e9r\u00eat et notre int\u00e9r\u00eat \u00e0 respecter les exigences l\u00e9gales lors de l&rsquo;envoi de newsletters (int\u00e9r\u00eat l\u00e9gitime au sens de l&rsquo;article 6, paragraphe 1, point f du RGPD). Le stockage dans la liste noire n&rsquo;est pas limit\u00e9 dans le temps.      <strong>Vous pouvez vous opposer \u00e0 l&rsquo;enregistrement si vos int\u00e9r\u00eats pr\u00e9valent sur notre int\u00e9r\u00eat l\u00e9gitime.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus de d\u00e9tails, veuillez consulter la politique de confidentialit\u00e9 de Brevo \u00e0 l&rsquo;adresse <a href=\"https:\/\/www.brevo.com\/de\/datenschutz-uebersicht\/\" target=\"_blank\" rel=\"nofollow\">suivante : https:\/\/www.brevo.com\/de\/datenschutz-uebersicht\/<\/a> et <a href=\"https:\/\/www.brevo.com\/de\/legal\/privacypolicy\/\" target=\"_blank\" rel=\"nofollow\">https:\/\/www.brevo.com\/de\/legal\/privacypolicy\/.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Traitement des commandes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons conclu un contrat de traitement des commandes (CTP) pour l&rsquo;utilisation du service susmentionn\u00e9. Il s&rsquo;agit d&rsquo;un contrat prescrit par la l\u00e9gislation sur la protection des donn\u00e9es, qui garantit que celui-ci ne traite les donn\u00e9es personnelles des visiteurs de notre site web que conform\u00e9ment \u00e0 nos instructions et dans le respect du RGPD.<\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-3bae260f\"><div class=\"gb-container gb-container-3bae260f\" data-aos=\"fade-right\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:\">5. outils d&rsquo;analyse et publicit\u00e9<\/h2><\/div>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Matomo<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Utilisation de Matomo<\/strong><br>Ce site web utilise Matomo, un logiciel open source pour l&rsquo;analyse statistique de l&rsquo;acc\u00e8s des visiteurs. Matomo est install\u00e9 localement sur notre serveur, de sorte que toutes les donn\u00e9es collect\u00e9es sont stock\u00e9es et trait\u00e9es exclusivement sur notre propre serveur. Les donn\u00e9es ne sont pas transmises \u00e0 des tiers.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Traitement des donn\u00e9es<\/strong><br>Matomo utilise des \u00ab\u00a0cookies\u00a0\u00bb, de petits fichiers texte qui sont stock\u00e9s sur votre terminal et qui nous permettent d&rsquo;analyser l&rsquo;utilisation de notre site web. Les informations g\u00e9n\u00e9r\u00e9es par le cookie concernant votre utilisation de ce site web sont enregistr\u00e9es de mani\u00e8re anonyme et utilis\u00e9es exclusivement pour des \u00e9valuations statistiques afin d&rsquo;am\u00e9liorer notre offre. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Base juridique<\/strong><br>Le traitement des donn\u00e9es est bas\u00e9 sur votre consentement conform\u00e9ment \u00e0 l&rsquo;article 6, paragraphe 6. 1 lit. a RGPD. Vous pouvez retirer votre consentement \u00e0 tout moment en ajustant les param\u00e8tres des cookies dans votre navigateur ou en d\u00e9sactivant le suivi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Anonymisation IP<\/strong><br>Votre adresse IP est anonymis\u00e9e avant d&rsquo;\u00eatre stock\u00e9e, ce qui exclut toute possibilit\u00e9 d&rsquo;identification directe des personnes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9sactivation de l&rsquo;analyse web<\/strong><br>Vous pouvez emp\u00eacher la collecte de vos donn\u00e9es par Matomo en utilisant la fonction opt-out suivante :<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conservation des donn\u00e9es<\/strong><br>Les donn\u00e9es collect\u00e9es sont exclusivement stock\u00e9es sur notre serveur et automatiquement supprim\u00e9es \u00e0 l&rsquo;expiration de la p\u00e9riode de stockage prescrite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Leadinfo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ce site web utilise le service de g\u00e9n\u00e9ration de leads de Leadinfo B.V., Rotterdam, Pays-Bas. Celui-ci reconna\u00eet les visites d&rsquo;entreprises sur notre site web \u00e0 l&rsquo;aide d&rsquo;adresses IP et nous montre \u00e0 cet effet des informations disponibles publiquement, comme par exemple le nom ou l&rsquo;adresse de l&rsquo;entreprise. En outre, Leadinfo place deux cookies de premi\u00e8re partie pour \u00e9valuer le comportement des utilisateurs sur notre site web et traite les domaines \u00e0 partir des entr\u00e9es de formulaires pour corr\u00e9ler les adresses IP avec les entreprises et am\u00e9liorer les services. Pour plus d&rsquo;informations, consultez le site www.leadinfo.com. Sur cette page : <a href=\"https:\/\/www.leadinfo.com\/en\/opt-out\" target=\"_blank\" rel=\"nofollow\">www.leadinfo.com\/en\/opt-out<\/a>, vous disposez d&rsquo;une possibilit\u00e9 d&rsquo;opt-out. En cas d&rsquo;opt-out, vos donn\u00e9es ne seront plus collect\u00e9es par Leadinfo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Google Analytics<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ce site web utilise les fonctions du service d&rsquo;analyse web Google Analytics. Le fournisseur est Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlande. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Google Analytics utilise ce que l&rsquo;on appelle des \u00ab\u00a0cookies\u00a0\u00bb. Il s&rsquo;agit de fichiers texte qui sont enregistr\u00e9s sur votre ordinateur et qui permettent d&rsquo;analyser votre utilisation du site web. Les informations g\u00e9n\u00e9r\u00e9es par le cookie concernant votre utilisation de ce site web sont g\u00e9n\u00e9ralement transmises \u00e0 un serveur de Google aux \u00c9tats-Unis et y sont enregistr\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le stockage des cookies de Google Analytics se fait sur la base de l&rsquo;article 6, paragraphe 6. 1 lit. a RGPD. L&rsquo;exploitant du site web a un int\u00e9r\u00eat l\u00e9gitime \u00e0 analyser le comportement des utilisateurs afin d&rsquo;optimiser \u00e0 la fois son offre web et sa publicit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Anonymisation des IP<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons activ\u00e9 la fonction d&rsquo;anonymisation IP sur ce site web. Ainsi, votre adresse IP sera raccourcie par Google dans les \u00c9tats membres de l&rsquo;Union europ\u00e9enne ou dans d&rsquo;autres \u00c9tats signataires de l&rsquo;accord sur l&rsquo;Espace \u00e9conomique europ\u00e9en avant d&rsquo;\u00eatre transmise aux \u00c9tats-Unis. Ce n&rsquo;est que dans des cas exceptionnels que l&rsquo;adresse IP compl\u00e8te est transmise \u00e0 un serveur de Google aux \u00c9tats-Unis et y est raccourcie. Google utilisera ces informations pour le compte de l&rsquo;exploitant de ce site web afin d&rsquo;\u00e9valuer votre utilisation du site web, de compiler des rapports sur les activit\u00e9s du site web et de fournir \u00e0 l&rsquo;exploitant du site web d&rsquo;autres services li\u00e9s \u00e0 l&rsquo;utilisation du site web et d&rsquo;Internet. L&rsquo;adresse IP transmise par votre navigateur dans le cadre de Google Analytics n&rsquo;est pas recoup\u00e9e avec d&rsquo;autres donn\u00e9es de Google.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Plugin de navigateur<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez emp\u00eacher l&rsquo;enregistrement des cookies en param\u00e9trant votre logiciel de navigation en cons\u00e9quence ; nous attirons toutefois votre attention sur le fait que, dans ce cas, vous ne pourrez peut-\u00eatre pas utiliser toutes les fonctions de ce site web dans leur int\u00e9gralit\u00e9. Vous pouvez en outre emp\u00eacher la saisie par Google des donn\u00e9es g\u00e9n\u00e9r\u00e9es par le cookie et se rapportant \u00e0 votre utilisation du site web (y compris votre adresse IP) ainsi que le traitement de ces donn\u00e9es par Google en t\u00e9l\u00e9chargeant et en installant le plug-in de navigateur disponible sous le lien suivant :<br><a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Traitement des donn\u00e9es de commande<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons conclu un contrat avec Google pour le traitement des donn\u00e9es de commande et appliquons int\u00e9gralement les directives strictes des autorit\u00e9s allemandes de protection des donn\u00e9es lors de l&rsquo;utilisation de Google Analytics.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Caract\u00e9ristiques d\u00e9mographiques dans Google Analytics<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce site utilise la fonction \u00ab\u00a0caract\u00e9ristiques d\u00e9mographiques\u00a0\u00bb de Google Analytics. Cela permet de cr\u00e9er des rapports contenant des d\u00e9clarations sur l&rsquo;\u00e2ge, le sexe et les int\u00e9r\u00eats des visiteurs du site. Ces donn\u00e9es proviennent de la publicit\u00e9 cibl\u00e9e par centres d&rsquo;int\u00e9r\u00eat de Google ainsi que de donn\u00e9es de visiteurs de fournisseurs tiers. Ces donn\u00e9es ne peuvent pas \u00eatre attribu\u00e9es \u00e0 une personne en particulier. Vous pouvez \u00e0 tout moment d\u00e9sactiver cette fonction via les param\u00e8tres des annonces dans votre compte Google ou interdire de mani\u00e8re g\u00e9n\u00e9rale la collecte de vos donn\u00e9es par Google Analytics comme indiqu\u00e9 au point \u00ab\u00a0Opposition \u00e0 la collecte de donn\u00e9es\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Google Ads<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;exploitant du site utilise Google Ads. Google Ads est un programme de publicit\u00e9 en ligne de Google Ireland Limited (\u00ab\u00a0Google\u00a0\u00bb), Gordon House, Barrow Street, Dublin 4, Irlande. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Google Ads permet de diffuser des annonces publicitaires dans le moteur de recherche Google ou sur des sites web de tiers lorsque l&rsquo;utilisateur saisit ou a saisi certains termes de recherche sur Google (ciblage par mots-cl\u00e9s). En outre, des annonces publicitaires cibl\u00e9es peuvent \u00eatre diffus\u00e9es \u00e0 l&rsquo;aide des donn\u00e9es utilisateur disponibles chez Google (par ex. donn\u00e9es de localisation et int\u00e9r\u00eats) (ciblage de groupes cibles). En tant qu&rsquo;exploitant du site Web, nous pouvons \u00e9valuer ces donn\u00e9es de mani\u00e8re quantitative, par exemple en analysant quels termes de recherche ont conduit \u00e0 la diffusion de nos annonces publicitaires et quelles annonces et combien d&rsquo;entre elles ont g\u00e9n\u00e9r\u00e9 des clics correspondants.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l&rsquo;article 6, paragraphe 6. 1 lit. a RGPD et \u00a7 25 al. 1 TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles types de la Commission europ\u00e9enne. Vous trouverez des d\u00e9tails ici : https:\/\/policies.google.com\/privacy\/frameworks et https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Google Ads Remarketing<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;exploitant du site web utilise les fonctions de Google Ads Remarketing. Le fournisseur est Google Ireland Limited (\u00ab\u00a0Google\u00a0\u00bb), Gordon House, Barrow Street, Dublin 4, Irlande. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Google Ads Remarketing nous permet d&rsquo;affecter des personnes qui utilisent notre offre en ligne ou interagissent avec elle \u00e0 des groupes cibles sp\u00e9cifiques, afin de leur afficher ensuite des publicit\u00e9s bas\u00e9es sur leurs centres d&rsquo;int\u00e9r\u00eat dans le r\u00e9seau publicitaire de Google (remarketing ou reciblage).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, les groupes cibles publicitaires cr\u00e9\u00e9s avec Google Ads Remarketing peuvent \u00eatre associ\u00e9s aux fonctionnalit\u00e9s inter-appareils de Google. De cette mani\u00e8re, les messages publicitaires personnalis\u00e9s en fonction de vos centres d&rsquo;int\u00e9r\u00eat, qui ont \u00e9t\u00e9 adapt\u00e9s \u00e0 vous en fonction de votre comportement d&rsquo;utilisation et de navigation ant\u00e9rieur sur un terminal (par ex. PC), peuvent \u00e9galement \u00eatre affich\u00e9s sur un autre de vos terminaux (par ex. t\u00e9l\u00e9phone mobile ou tablette). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous disposez d&rsquo;un compte Google, vous pouvez vous opposer \u00e0 cette forme de publicit\u00e9 personnalis\u00e9e en cliquant sur le lien suivant : https:\/\/www.google.com\/settings\/ads\/onweb\/.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l&rsquo;article 6, paragraphe 6. 1 lit. a RGPD et \u00a7 25 al. 1 TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous trouverez de plus amples informations et les dispositions relatives \u00e0 la protection des donn\u00e9es dans la d\u00e9claration de confidentialit\u00e9 de Google \u00e0 l&rsquo;adresse suivante : https:\/\/policies.google.com\/technologies\/ads?hl=de.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Suivi des conversions Google<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce site utilise Google Conversion Tracking. Le fournisseur est Google Ireland Limited (\u00ab\u00a0Google\u00a0\u00bb), Gordon House, Barrow Street, Dublin 4, Irlande. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce au suivi des conversions de Google, Google et nous-m\u00eames pouvons savoir si l&rsquo;utilisateur a effectu\u00e9 certaines actions et comment le client a utilis\u00e9 notre site Web. Par exemple, nous pouvons \u00e9valuer quels boutons de notre site Web ont \u00e9t\u00e9 cliqu\u00e9s \u00e0 quelle fr\u00e9quence et quels produits ont \u00e9t\u00e9 particuli\u00e8rement consult\u00e9s ou achet\u00e9s. Ces informations nous permettent d&rsquo;\u00e9tablir des statistiques. Nous connaissons le nombre total d&rsquo;utilisateurs qui ont cliqu\u00e9 sur nos annonces et les actions qu&rsquo;ils ont effectu\u00e9es. Nous n&rsquo;obtenons ainsi aucune information qui nous permettrait d&rsquo;identifier personnellement l&rsquo;utilisateur. Google lui-m\u00eame utilise des cookies ou des technologies de reconnaissance comparables pour l&rsquo;identification.     <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;utilisation de ce service se fait sur la base de votre consentement conform\u00e9ment \u00e0 l&rsquo;article 6, paragraphe 6. 1 lit. a RGPD et \u00a7 25 al. 1 TDDDG. Le consentement est r\u00e9vocable \u00e0 tout moment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour en savoir plus sur le suivi des conversions de Google, consultez les r\u00e8gles de confidentialit\u00e9 de Google : https:\/\/policies.google.com\/privacy?hl=de.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Consentement avec le cookie de Borlab<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Notre site web utilise la technologie Consent de Borlabs Cookie pour obtenir votre consentement au stockage de certains cookies dans votre navigateur ou \u00e0 l&rsquo;utilisation de certaines technologies et pour documenter ce consentement conform\u00e9ment \u00e0 la protection des donn\u00e9es. Le fournisseur de cette technologie est Borlabs GmbH, R\u00fcbenkamp 32, 22305 Hambourg (ci-apr\u00e8s Borlabs). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous acc\u00e9dez \u00e0 notre site web, un cookie Borlabs est stock\u00e9 dans votre navigateur, dans lequel les consentements que vous avez donn\u00e9s ou le retrait de ces consentements<br>sont enregistr\u00e9s. Ces donn\u00e9es ne sont pas partag\u00e9es avec le fournisseur du cookie Borlabs. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es collect\u00e9es sont conserv\u00e9es jusqu&rsquo;\u00e0 ce que vous nous demandiez de les supprimer, ou jusqu&rsquo;\u00e0 ce que vous supprimiez vous-m\u00eame le cookie Borlabs, ou jusqu&rsquo;\u00e0 ce que le but de la conservation des donn\u00e9es ne soit plus valable. Les p\u00e9riodes de conservation l\u00e9gales obligatoires ne sont pas affect\u00e9es. Pour plus de d\u00e9tails sur le traitement des donn\u00e9es par le cookie de Borlab, veuillez <a href=\"https:\/\/de.borlabs.io\/kb\/welchedaten-speichert-borlabs-cookie\/\" target=\"_blank\" rel=\"nofollow\">consulter https:\/\/de.borlabs.io\/kb\/welchedaten-speichert-borlabs-cookie\/.<\/a>  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;utilisation de la technologie de consentement aux cookies de Borlabs a lieu afin d&rsquo;obtenir les consentements requis par la loi pour l&rsquo;utilisation de cookies.<br>La base juridique pour cela est l&rsquo;article 6, paragraphe 1. 1 lit. c du RGPD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Youtube<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nous disposons d&rsquo;un profil sur YouTube. Le fournisseur est Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlande. Pour plus de d\u00e9tails sur la mani\u00e8re dont ils traitent vos donn\u00e9es personnelles<br>, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de YouTube <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"nofollow\">: https:\/\/policies.google.com\/privacy?hl=de.<\/a>  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;entreprise dispose d&rsquo;une certification selon le \u00ab\u00a0EU-US Data Privacy Framework\u00a0\u00bb (DPF). Le DPF est un accord entre l&rsquo;Union europ\u00e9enne et les \u00c9tats-Unis visant \u00e0 garantir le respect des normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es lors du traitement de donn\u00e9es aux \u00c9tats-Unis. Toute entreprise certifi\u00e9e DPF s&rsquo;engage \u00e0 respecter ces normes de protection des donn\u00e9es. Pour plus d&rsquo;informations \u00e0 ce sujet, veuillez contacter le fournisseur en cliquant sur le lien suivant : <a href=\"https:\/\/www.dataprivacyframework.gov\/participant\/5780\" target=\"_blank\" rel=\"nofollow\">https:\/\/www.dataprivacyframework.gov\/participant\/5780<\/a>   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Microsoft Clarity<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nous travaillons avec Microsoft Clarity et Microsoft Advertising pour enregistrer la mani\u00e8re dont vous utilisez et interagissez avec notre site Web, \u00e0 l&rsquo;aide de mesures comportementales, de cartes de chaleur et de sessions r\u00e9p\u00e9t\u00e9es, afin d&rsquo;am\u00e9liorer et de commercialiser nos produits et services. Les donn\u00e9es d&rsquo;utilisation du site sont collect\u00e9es \u00e0 l&rsquo;aide de cookies de premi\u00e8re et de troisi\u00e8me g\u00e9n\u00e9ration et d&rsquo;autres technologies de suivi afin de d\u00e9terminer la popularit\u00e9 des produits\/services et des activit\u00e9s en ligne. Nous utilisons \u00e9galement ces informations pour optimiser le site, \u00e0 des fins de fraude\/s\u00e9curit\u00e9 et de publicit\u00e9. Pour plus d&rsquo;informations sur la mani\u00e8re dont Microsoft collecte et utilise vos donn\u00e9es, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de Microsoft <a href=\"https:\/\/privacy.microsoft.com\/de-DE\/privacystatement\" target=\"_blank\" rel=\"nofollow\">: https:\/\/privacy.microsoft.com\/de-DE\/privacystatement<\/a>   <\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:\">6. Commerce \u00e9lectronique et fournisseurs de paiement<\/h2><\/div>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Traitement des donn\u00e9es clients et des donn\u00e9es contractuelles<br><\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nous collectons, traitons et utilisons les donn\u00e9es personnelles des clients et les donn\u00e9es contractuelles pour \u00e9tablir, d\u00e9finir le contenu et modifier nos relations contractuelles. Nous ne collectons, traitons et utilisons les donn\u00e9es personnelles relatives \u00e0 l&rsquo;utilisation de ce site web (donn\u00e9es d&rsquo;utilisation) que dans la mesure o\u00f9 cela est n\u00e9cessaire pour permettre \u00e0 l&rsquo;utilisateur d&rsquo;utiliser le service ou de le facturer. La base juridique est l&rsquo;art. 6, al. 1 lit. b du RGPD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es clients collect\u00e9es sont supprim\u00e9es apr\u00e8s l&rsquo;ach\u00e8vement de la commande ou la fin de la relation commerciale et l&rsquo;expiration des d\u00e9lais de conservation l\u00e9gaux \u00e9ventuellement existants. Les d\u00e9lais de conservation l\u00e9gaux ne sont pas affect\u00e9s.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:\">7. services propres<\/h2><\/div>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Traitement des donn\u00e9es des candidats<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous offrons la possibilit\u00e9 de postuler chez nous (par exemple par e-mail, par courrier ou via le formulaire de candidature en ligne). Nous vous informons ci-apr\u00e8s de l&rsquo;\u00e9tendue, de la finalit\u00e9 et de l&rsquo;utilisation de vos donn\u00e9es personnelles collect\u00e9es dans le cadre du processus de candidature. Nous vous assurons que la collecte, le traitement et l&rsquo;utilisation de vos donn\u00e9es sont conformes \u00e0 la l\u00e9gislation en vigueur sur la protection des donn\u00e9es et \u00e0 toutes les autres dispositions l\u00e9gales et que vos donn\u00e9es sont trait\u00e9es de mani\u00e8re strictement confidentielle.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Port\u00e9e et objectif de la collecte de donn\u00e9es<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous nous envoyez une candidature, nous traitons les donn\u00e9es \u00e0 caract\u00e8re personnel qui y sont li\u00e9es (par exemple, les donn\u00e9es de contact et de communication, les documents de candidature, les notes prises dans le cadre d&rsquo;entretiens d&#8217;embauche, etc.), dans la mesure o\u00f9 cela est n\u00e9cessaire pour d\u00e9cider de l&rsquo;\u00e9tablissement d&rsquo;une relation d&#8217;emploi. La base juridique pour cela est le \u00a7 26 BDSG selon le droit allemand (initiation d&rsquo;une relation d&#8217;emploi), l&rsquo;art. 6 al. 1 lit. b RGPD (pr\u00e9paration g\u00e9n\u00e9rale du contrat) et &#8211; si vous avez donn\u00e9 votre consentement &#8211; l&rsquo;art. 6, al. 1 lit. a RGPD. Le consentement est r\u00e9vocable \u00e0 tout moment. Vos donn\u00e9es personnelles ne seront transmises au sein de notre entreprise qu&rsquo;aux personnes impliqu\u00e9es dans le traitement de votre candidature.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si la candidature est retenue, les donn\u00e9es que vous avez soumises seront trait\u00e9es sur la base de l&rsquo;article 26 de la loi f\u00e9d\u00e9rale sur la protection des donn\u00e9es (BDSG) et de l&rsquo;article 6, paragraphe 1, de la loi f\u00e9d\u00e9rale sur la protection des donn\u00e9es (LPD). 1 lit. b RGPD dans nos syst\u00e8mes de traitement des donn\u00e9es aux fins de l&rsquo;ex\u00e9cution de la relation d&#8217;emploi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le formulaire de contact, nous collectons \u00e0 la fois votre nom et votre e-mail. Nous pouvons ainsi nous adresser personnellement \u00e0 vous dans notre r\u00e9ponse. Vos droits en tant que personne concern\u00e9e restent inchang\u00e9s.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Dur\u00e9e de conservation des donn\u00e9es<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la mesure o\u00f9 nous ne pouvons pas vous proposer d&rsquo;offre d&#8217;emploi, o\u00f9 vous refusez une offre d&#8217;emploi ou retirez votre candidature, nous nous r\u00e9servons le droit de conserver chez nous les donn\u00e9es que vous nous avez transmises, sur la base de nos int\u00e9r\u00eats l\u00e9gitimes (article 6, paragraphe 1, point f du RGPD), pendant une dur\u00e9e maximale de 6 mois \u00e0 compter de la fin de la proc\u00e9dure de candidature (refus ou retrait de la candidature). Ensuite, les donn\u00e9es sont effac\u00e9es et les dossiers de candidature physiques sont d\u00e9truits. La conservation sert notamment \u00e0 des fins de preuve en cas de litige. S&rsquo;il est \u00e9vident que les donn\u00e9es seront n\u00e9cessaires apr\u00e8s l&rsquo;expiration du d\u00e9lai de six mois (par exemple en raison d&rsquo;un litige imminent ou en cours), elles ne seront supprim\u00e9es que lorsque la finalit\u00e9 de leur conservation ult\u00e9rieure n&rsquo;aura plus lieu d&rsquo;\u00eatre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une conservation plus longue peut en outre avoir lieu si vous avez donn\u00e9 votre consentement (article 6, paragraphe 1, point a) du RGPD) ou si des obligations l\u00e9gales de conservation s&rsquo;opposent \u00e0 l&rsquo;effacement.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Int\u00e9gration dans le pool de candidats<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Si nous ne vous proposons pas d&rsquo;offre d&#8217;emploi, il est \u00e9ventuellement possible de vous int\u00e9grer dans notre pool de candidats. En cas d&rsquo;admission, tous les documents et donn\u00e9es de la candidature sont repris dans le pool de candidats afin de vous contacter en cas de postes vacants correspondants.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;int\u00e9gration dans le pool de candidats se fait exclusivement sur la base de votre consentement explicite (article 6, paragraphe 1, point a du RGPD). La remise du consentement est volontaire et n&rsquo;a aucun rapport avec la proc\u00e9dure de candidature en cours. <strong>La personne concern\u00e9e peut r\u00e9voquer son consentement \u00e0 tout moment<\/strong>. Dans ce cas, les donn\u00e9es seront irr\u00e9vocablement supprim\u00e9es du vivier de candidats, \u00e0 moins qu&rsquo;il n&rsquo;existe des raisons l\u00e9gales de les conserver.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es du pool de candidats sont irr\u00e9vocablement supprim\u00e9es au plus tard deux ans apr\u00e8s l&rsquo;octroi du consentement.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Inscription sur ce site<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez vous inscrire sur ce site afin d&rsquo;utiliser des fonctions suppl\u00e9mentaires sur le site. Nous n&rsquo;utiliserons les donn\u00e9es saisies \u00e0 cet effet qu&rsquo;aux fins de l&rsquo;utilisation de l&rsquo;offre ou du service respectif pour lequel vous vous \u00eates enregistr\u00e9. Les informations obligatoires demand\u00e9es lors de l&rsquo;enregistrement doivent \u00eatre fournies dans leur int\u00e9gralit\u00e9. Dans le cas contraire, nous refuserons l&rsquo;enregistrement.<br>En cas de modifications importantes, par exemple concernant l&rsquo;\u00e9tendue de l&rsquo;offre ou en cas de modifications n\u00e9cessaires sur le plan technique, nous utilisons l&rsquo;adresse e-mail indiqu\u00e9e lors de l&rsquo;enregistrement pour vous informer par ce biais.<br>Le traitement des donn\u00e9es saisies lors de l&rsquo;enregistrement a pour but d&rsquo;ex\u00e9cuter la relation d&rsquo;utilisation \u00e9tablie par l&rsquo;enregistrement et, le cas \u00e9ch\u00e9ant, de pr\u00e9parer d&rsquo;autres contrats (art. 6, par. 1, point b du RGPD).<br>Les donn\u00e9es saisies lors de l&rsquo;enregistrement sont conserv\u00e9es par nous tant que vous \u00eates enregistr\u00e9 sur ce site Internet et sont ensuite effac\u00e9es.    Les d\u00e9lais de conservation l\u00e9gaux ne sont pas affect\u00e9s.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline\" style=\"color:\">8. notre pr\u00e9sence sur les m\u00e9dias sociaux<\/h2><\/div>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Traitement des donn\u00e9es par les r\u00e9seaux sociaux<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nous g\u00e9rons des profils accessibles au public sur les r\u00e9seaux sociaux. Vous trouverez ci-dessous le d\u00e9tail des r\u00e9seaux sociaux que nous utilisons.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les r\u00e9seaux sociaux tels que Facebook, Twitter, etc. peuvent g\u00e9n\u00e9ralement analyser de mani\u00e8re approfondie votre comportement d&rsquo;utilisateur lorsque vous visitez leur site web ou un site web int\u00e9grant des contenus de m\u00e9dias sociaux (par exemple des boutons \u00ab\u00a0J&rsquo;aime\u00a0\u00bb ou des banni\u00e8res publicitaires). La visite de nos pr\u00e9sences sur les m\u00e9dias sociaux d\u00e9clenche de nombreux processus de traitement relatifs \u00e0 la protection des donn\u00e9es. En d\u00e9tail :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous \u00eates connect\u00e9 \u00e0 votre compte de m\u00e9dias sociaux et que vous visitez notre pr\u00e9sence sur les m\u00e9dias sociaux, l&rsquo;exploitant du portail de m\u00e9dias sociaux peut attribuer cette visite \u00e0 votre compte d&rsquo;utilisateur. Vos donn\u00e9es personnelles peuvent \u00e9galement \u00eatre collect\u00e9es si vous n&rsquo;\u00eates pas connect\u00e9(e) ou si vous ne poss\u00e9dez pas de compte sur le portail de m\u00e9dias sociaux concern\u00e9. Dans ce cas, cette collecte de donn\u00e9es s&rsquo;effectue par exemple par le biais de cookies qui sont enregistr\u00e9s sur votre terminal ou par la saisie de votre adresse IP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es ainsi collect\u00e9es permettent aux exploitants des portails de m\u00e9dias sociaux de cr\u00e9er des profils d&rsquo;utilisateurs dans lesquels sont enregistr\u00e9s vos pr\u00e9f\u00e9rences et vos int\u00e9r\u00eats. De cette mani\u00e8re, des publicit\u00e9s bas\u00e9es sur vos int\u00e9r\u00eats peuvent vous \u00eatre pr\u00e9sent\u00e9es dans et en dehors de la pr\u00e9sence du m\u00e9dia social concern\u00e9. Si vous disposez d&rsquo;un compte sur le r\u00e9seau social concern\u00e9, la publicit\u00e9 cibl\u00e9e par centres d&rsquo;int\u00e9r\u00eat peut \u00eatre affich\u00e9e sur tous les appareils sur lesquels vous \u00eates ou avez \u00e9t\u00e9 connect\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez \u00e9galement noter que nous ne pouvons pas suivre tous les processus de traitement sur les portails de m\u00e9dias sociaux. Selon le fournisseur, d&rsquo;autres op\u00e9rations de traitement peuvent donc \u00e9ventuellement \u00eatre effectu\u00e9es par les exploitants des portails de m\u00e9dias sociaux. Pour plus de d\u00e9tails, veuillez consulter les conditions d&rsquo;utilisation et les dispositions relatives \u00e0 la protection des donn\u00e9es des portails de m\u00e9dias sociaux concern\u00e9s.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Base juridique<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Notre pr\u00e9sence sur les m\u00e9dias sociaux doit garantir une pr\u00e9sence aussi compl\u00e8te que possible sur Internet. Il s&rsquo;agit d&rsquo;un int\u00e9r\u00eat l\u00e9gitime au sens de l&rsquo;article 6, paragraphe 1, de la loi sur la protection des donn\u00e9es. 1 lit. f du RGPD. Les processus d&rsquo;analyse initi\u00e9s par les r\u00e9seaux sociaux reposent, le cas \u00e9ch\u00e9ant, sur des bases juridiques divergentes qui doivent \u00eatre indiqu\u00e9es par les exploitants des r\u00e9seaux sociaux (par ex. consentement au sens de l&rsquo;art. 6, al. 1, let. a du RGPD).<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Responsable et exercice des droits<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous visitez l&rsquo;un de nos sites de m\u00e9dias sociaux (par exemple Facebook), nous sommes responsables, conjointement avec l&rsquo;exploitant de la plateforme de m\u00e9dias sociaux, des processus de traitement des donn\u00e9es d\u00e9clench\u00e9s lors de cette visite. Vous pouvez en principe exercer vos droits (information, rectification, effacement, limitation du traitement, portabilit\u00e9 des donn\u00e9es et r\u00e9clamation) aussi bien \u00e0 l&rsquo;\u00e9gard de l&rsquo;entreprise que de la personne concern\u00e9e. \u00e0 notre \u00e9gard et \u00e0 l&rsquo;\u00e9gard de l&rsquo;exploitant du portail de m\u00e9dias sociaux concern\u00e9 (par exemple, Facebook).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez noter que, malgr\u00e9 la responsabilit\u00e9 partag\u00e9e avec les exploitants des portails de m\u00e9dias sociaux, nous n&rsquo;avons pas une influence totale sur les processus de traitement des donn\u00e9es des portails de m\u00e9dias sociaux. Nos possibilit\u00e9s d\u00e9pendent en grande partie de la politique d&rsquo;entreprise du fournisseur concern\u00e9.<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Dur\u00e9e de stockage<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es que nous collectons directement via la pr\u00e9sence sur les m\u00e9dias sociaux sont supprim\u00e9es de nos syst\u00e8mes d\u00e8s que vous nous demandez de les supprimer, que vous r\u00e9voquez votre consentement \u00e0 leur stockage ou que la finalit\u00e9 du stockage des donn\u00e9es n&rsquo;est plus valable. Les cookies enregistr\u00e9s restent sur votre terminal jusqu&rsquo;\u00e0 ce que vous les supprimiez. Dispositions l\u00e9gales contraignantes &#8211; en particulier les d\u00e9lais de conservation &#8211; ne sont pas affect\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous n&rsquo;avons aucune influence sur la dur\u00e9e de conservation de vos donn\u00e9es, qui sont enregistr\u00e9es par les exploitants des r\u00e9seaux sociaux \u00e0 leurs propres fins. Pour plus de d\u00e9tails, veuillez vous informer directement aupr\u00e8s des exploitants des r\u00e9seaux sociaux (par exemple dans leur d\u00e9claration de protection des donn\u00e9es, voir ci-dessous).<\/p>\n\n\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h3 class=\"headline\" style=\"color:\">Les r\u00e9seaux sociaux en d\u00e9tail<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Facebook<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous disposons d&rsquo;un profil sur Facebook. Le fournisseur de ce service est Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irlande (ci-apr\u00e8s d\u00e9nomm\u00e9 Meta). Selon Meta, les donn\u00e9es collect\u00e9es sont \u00e9galement transf\u00e9r\u00e9es aux \u00c9tats-Unis et dans d&rsquo;autres pays tiers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vous pouvez adapter vous-m\u00eame vos param\u00e8tres publicitaires dans votre compte d&rsquo;utilisateur. Pour ce faire, cliquez sur le lien suivant et connectez-vous :<\/strong> <a href=\"https:\/\/www.facebook.com\/settings?tab=ads\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/www.facebook.com\/settings?tab=ads.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles types de la Commission europ\u00e9enne. Vous trouverez des d\u00e9tails ici <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">: https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a> et <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/de-de.facebook.com\/help\/566994660333381.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus de d\u00e9tails, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de Facebook <a rel=\"noreferrer noopener nofollow\" href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\">: https:\/\/www.facebook.com\/about\/privacy\/.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Twitter<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous utilisons le service de messages courts Twitter. Le fournisseur est Twitter International Company, One Cumberland Place, Fenian Street, Dublin 2, D02 AX07, Irlande.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vous pouvez modifier vous-m\u00eame vos param\u00e8tres de confidentialit\u00e9 Twitter dans votre compte d&rsquo;utilisateur. Pour ce faire, cliquez sur le lien suivant et connectez-vous <a href=\"https:\/\/twitter.com\/personalization\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">: https:\/\/twitter.com\/personalization.<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles types de la Commission europ\u00e9enne. Vous trouverez des d\u00e9tails ici <a href=\"https:\/\/gdpr.twitter.com\/en\/controller-to-controller-transfers.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">: https:\/\/gdpr.twitter.com\/en\/controller-to-controller-transfers.html.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus de d\u00e9tails, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de Twitter <a rel=\"noreferrer noopener nofollow\" href=\"https:\/\/twitter.com\/privacy\" target=\"_blank\">: https:\/\/twitter.com\/privacy.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Instagram<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous disposons d&rsquo;un profil sur Instagram. Le fournisseur de ce service est Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irlande.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles types de la Commission europ\u00e9enne. Vous trouverez des d\u00e9tails ici :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum,<\/a> <a href=\"https:\/\/help.instagram.com\/519522125107875\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/help.instagram.com\/519522125107875<\/a> et <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/de-de.facebook.com\/help\/566994660333381.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus de d\u00e9tails sur la mani\u00e8re dont ils traitent vos donn\u00e9es personnelles, veuillez consulter la d\u00e9claration de confidentialit\u00e9 d&rsquo;Instagram <a rel=\"noreferrer noopener nofollow\" href=\"https:\/\/help.instagram.com\/519522125107875\" target=\"_blank\">: https:\/\/help.instagram.com\/519522125107875.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>XING<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous disposons d&rsquo;un profil sur XING. Le fournisseur est New Work SE, Dammtorstra\u00dfe 30, 20354 Hambourg, Allemagne. Pour plus de d\u00e9tails sur leur traitement de vos donn\u00e9es personnelles, veuillez consulter la d\u00e9claration de protection des donn\u00e9es de XING :<br><a rel=\"noreferrer noopener nofollow\" href=\"https:\/\/privacy.xing.com\/de\/datenschutzerklaerung\" target=\"_blank\">https:\/\/privacy.xing.com\/de\/datenschutzerklaerung.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LinkedIn<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous disposons d&rsquo;un profil sur LinkedIn. Le fournisseur est LinkedIn Ireland Unlimited Company, Wilton Plaza, Wilton Place, Dublin 2, Irlande. LinkedIn utilise des cookies publicitaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Si vous souhaitez d\u00e9sactiver les cookies publicitaires de LinkedIn, veuillez utiliser le lien suivant : <\/strong><a href=\"https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le transfert de donn\u00e9es vers les \u00c9tats-Unis est bas\u00e9 sur les clauses contractuelles types de la Commission europ\u00e9enne. Vous trouverez des d\u00e9tails ici <a href=\"https:\/\/www.linkedin.com\/legal\/l\/dpa\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">: https:\/\/www.linkedin.com\/legal\/l\/dpa<\/a> et <a href=\"https:\/\/www.linkedin.com\/legal\/l\/eu-sccs\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/www.linkedin.com\/legal\/l\/eu-sccs.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus de d\u00e9tails sur la mani\u00e8re dont ils traitent vos donn\u00e9es personnelles, veuillez consulter la d\u00e9claration de confidentialit\u00e9 de LinkedIn <a rel=\"noreferrer noopener nofollow\" href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\">: https:\/\/www.linkedin.com\/legal\/privacy-policy.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Solingen me fait bouger<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous disposons d&rsquo;un profil sur \u00ab\u00a0Solingen bewegt mich\u00a0\u00bb (Solingen me fait bouger). Le fournisseur est Porombka GmbH, Kauffunger Weg 8, 42699 Solingen, Allemagne.<\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":18,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7756","page","type-page","status-publish","no-featured-image-padding"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protection des donn\u00e9es chez LUTZ BLADES<\/title>\n<meta name=\"description\" content=\"Dans notre d\u00e9claration de protection des donn\u00e9es, nous donnons un aper\u00e7u de la collecte et du traitement des donn\u00e9es personnelles sur notre site web.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lutz-blades.com\/fr\/protection-des-donnees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protection des donn\u00e9es chez LUTZ BLADES\" \/>\n<meta property=\"og:description\" content=\"Dans notre d\u00e9claration de protection des donn\u00e9es, nous donnons un aper\u00e7u de la collecte et du traitement des donn\u00e9es personnelles sur notre site web.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lutz-blades.com\/fr\/protection-des-donnees\/\" \/>\n<meta property=\"og:site_name\" content=\"LUTZ BLADES exactly\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-03T14:37:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"42 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/protection-des-donnees\\\/\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/protection-des-donnees\\\/\",\"name\":\"Protection des donn\u00e9es chez LUTZ BLADES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#website\"},\"datePublished\":\"2023-04-28T07:41:37+00:00\",\"dateModified\":\"2025-06-03T14:37:17+00:00\",\"description\":\"Dans notre d\u00e9claration de protection des donn\u00e9es, nous donnons un aper\u00e7u de la collecte et du traitement des donn\u00e9es personnelles sur notre site web.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/protection-des-donnees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/protection-des-donnees\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/protection-des-donnees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protection des donn\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/\",\"name\":\"LUTZ BLADES exactly\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#organization\",\"name\":\"LUTZ BLADES exactly\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/lutz-blades-logo.svg\",\"contentUrl\":\"https:\\\/\\\/lutz-blades.com\\\/wp-content\\\/uploads\\\/lutz-blades-logo.svg\",\"width\":240,\"height\":66,\"caption\":\"LUTZ BLADES exactly\"},\"image\":{\"@id\":\"https:\\\/\\\/lutz-blades.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protection des donn\u00e9es chez LUTZ BLADES","description":"Dans notre d\u00e9claration de protection des donn\u00e9es, nous donnons un aper\u00e7u de la collecte et du traitement des donn\u00e9es personnelles sur notre site web.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lutz-blades.com\/fr\/protection-des-donnees\/","og_locale":"fr_FR","og_type":"article","og_title":"Protection des donn\u00e9es chez LUTZ BLADES","og_description":"Dans notre d\u00e9claration de protection des donn\u00e9es, nous donnons un aper\u00e7u de la collecte et du traitement des donn\u00e9es personnelles sur notre site web.","og_url":"https:\/\/lutz-blades.com\/fr\/protection-des-donnees\/","og_site_name":"LUTZ BLADES exactly","article_modified_time":"2025-06-03T14:37:17+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"42 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lutz-blades.com\/fr\/protection-des-donnees\/","url":"https:\/\/lutz-blades.com\/fr\/protection-des-donnees\/","name":"Protection des donn\u00e9es chez LUTZ BLADES","isPartOf":{"@id":"https:\/\/lutz-blades.com\/fr\/#website"},"datePublished":"2023-04-28T07:41:37+00:00","dateModified":"2025-06-03T14:37:17+00:00","description":"Dans notre d\u00e9claration de protection des donn\u00e9es, nous donnons un aper\u00e7u de la collecte et du traitement des donn\u00e9es personnelles sur notre site web.","breadcrumb":{"@id":"https:\/\/lutz-blades.com\/fr\/protection-des-donnees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lutz-blades.com\/fr\/protection-des-donnees\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lutz-blades.com\/fr\/protection-des-donnees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/lutz-blades.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Protection des donn\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/lutz-blades.com\/fr\/#website","url":"https:\/\/lutz-blades.com\/fr\/","name":"LUTZ BLADES exactly","description":"","publisher":{"@id":"https:\/\/lutz-blades.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lutz-blades.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lutz-blades.com\/fr\/#organization","name":"LUTZ BLADES exactly","url":"https:\/\/lutz-blades.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lutz-blades.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-logo.svg","contentUrl":"https:\/\/lutz-blades.com\/wp-content\/uploads\/lutz-blades-logo.svg","width":240,"height":66,"caption":"LUTZ BLADES exactly"},"image":{"@id":"https:\/\/lutz-blades.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/pages\/7756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/comments?post=7756"}],"version-history":[{"count":21,"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/pages\/7756\/revisions"}],"predecessor-version":[{"id":85844,"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/pages\/7756\/revisions\/85844"}],"wp:attachment":[{"href":"https:\/\/lutz-blades.com\/fr\/wp-json\/wp\/v2\/media?parent=7756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}